{"id":70302,"date":"2021-02-07T22:52:58","date_gmt":"2021-02-07T21:52:58","guid":{"rendered":"https:\/\/dlvradio.es\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/"},"modified":"2021-02-07T22:52:58","modified_gmt":"2021-02-07T21:52:58","slug":"un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/","title":{"rendered":"Un gran negocio llamado inexistente S\u00edndrome de Alienaci\u00f3n Parental (iSAP)"},"content":{"rendered":"<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: Un gran negocio llamado inexistente S\u00edndrome de Alienaci\u00f3n Parental (iSAP)\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/4Kw3FwOtxDA9ItSdRRa6S5?si=Ti1BSIQwQvK5UBu1ebAxKA&#038;utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n\n<p><img decoding=\"async\" class=\"alignleft wp-image-5987 size-thumbnail\" src=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/02\/Un-gran-negocio-llamado-inexistente-Sindrome-de-Alienacion-Parental-iSAP-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>Nadie sabe, a menos que lo haya vivido, lo que supone que te arranquen a tu hija. El d\u00eda que a m\u00ed me la arrancaron mor\u00ed, mor\u00ed en vida. Pegu\u00e9 mis pedacitos para poder salir del Servicio de Infancia que fue donde ocurri\u00f3 y al salir, me sent\u00ed vac\u00eda, sin vida. No sab\u00eda qu\u00e9 hacer, ni a d\u00f3nde acudir. Mi cuerpo estaba amoratado, pero me dol\u00eda el alma.<\/p>\n<p>Nunca asimilas lo que te ha pasado porque tu mente no entiende tanto dolor, tanto sufrimiento, tanta maldad. Lloras y lloras. Escuchas su respiraci\u00f3n mientras est\u00e1s en la cama, la oyes llam\u00e1ndote en sue\u00f1os, sientes su dolor y a la vez, no la puedes ayudar y te ves inmersa en una impotencia que te genera una grand\u00edsima frustraci\u00f3n.<\/p>\n<p>Por <strong>Iru\u00f1e Costumero<\/strong> de la Asociaci\u00f3n La Volaera. V\u00eda <a href=\"https:\/\/nuevarevolucion.es\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/\">Nueva Revoluci\u00f3n<\/a>.<\/p>\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Nadie sabe, a menos que lo haya vivido, lo que supone que te arranquen a tu hija. El d\u00eda que a m\u00ed me la arrancaron mor\u00ed, mor\u00ed en vida. Pegu\u00e9 mis pedacitos para poder salir del Servicio de Infancia que fue donde ocurri\u00f3 y al salir, me sent\u00ed vac\u00eda, sin vida. No sab\u00eda qu\u00e9 hacer, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2470,2465],"tags":[2530,2471,2566],"class_list":["post-70302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-feminismo","category-informativos","tag-actualidad","tag-feminismo","tag-leyes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un gran negocio llamado inexistente S\u00edndrome de Alienaci\u00f3n Parental (iSAP) - DLVRADIO<\/title>\n<meta name=\"description\" content=\"https:\/\/open.spotify.com\/episode\/4Kw3FwOtxDA9ItSdRRa6S5?si=Ti1BSIQwQvK5UBu1ebAxKA Nadie sabe, a menos que lo haya vivido, lo que supone que te arranquen a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un gran negocio llamado inexistente S\u00edndrome de Alienaci\u00f3n Parental (iSAP) - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"https:\/\/open.spotify.com\/episode\/4Kw3FwOtxDA9ItSdRRa6S5?si=Ti1BSIQwQvK5UBu1ebAxKA Nadie sabe, a menos que lo haya vivido, lo que supone que te arranquen a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-07T21:52:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/02\/Un-gran-negocio-llamado-inexistente-Sindrome-de-Alienacion-Parental-iSAP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1511\" \/>\n\t<meta property=\"og:image:height\" content=\"1511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DLV RADIO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\\\/\"},\"author\":{\"name\":\"DLV RADIO\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\"},\"headline\":\"Un gran negocio llamado inexistente S\u00edndrome de Alienaci\u00f3n Parental (iSAP)\",\"datePublished\":\"2021-02-07T21:52:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\\\/\"},\"wordCount\":178,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Un-gran-negocio-llamado-inexistente-Sindrome-de-Alienacion-Parental-iSAP.jpg\",\"keywords\":[\"actualidad\",\"feminismo\",\"leyes\"],\"articleSection\":[\"Feminismo\",\"Informativos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\\\/\",\"name\":\"Un gran negocio llamado inexistente S\u00edndrome de Alienaci\u00f3n Parental (iSAP) - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Un-gran-negocio-llamado-inexistente-Sindrome-de-Alienacion-Parental-iSAP.jpg\",\"datePublished\":\"2021-02-07T21:52:58+00:00\",\"description\":\"https:\\\/\\\/open.spotify.com\\\/episode\\\/4Kw3FwOtxDA9ItSdRRa6S5?si=Ti1BSIQwQvK5UBu1ebAxKA Nadie sabe, a menos que lo haya vivido, lo que supone que te arranquen a\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Un-gran-negocio-llamado-inexistente-Sindrome-de-Alienacion-Parental-iSAP.jpg\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Un-gran-negocio-llamado-inexistente-Sindrome-de-Alienacion-Parental-iSAP.jpg\",\"width\":1511,\"height\":1511,\"caption\":\"Un gran negocio llamado inexistente S\u00edndrome de Alienaci\u00f3n Parental (iSAP)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un gran negocio llamado inexistente S\u00edndrome de Alienaci\u00f3n Parental (iSAP)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\",\"name\":\"DLV RADIO\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un gran negocio llamado inexistente S\u00edndrome de Alienaci\u00f3n Parental (iSAP) - DLVRADIO","description":"https:\/\/open.spotify.com\/episode\/4Kw3FwOtxDA9ItSdRRa6S5?si=Ti1BSIQwQvK5UBu1ebAxKA Nadie sabe, a menos que lo haya vivido, lo que supone que te arranquen a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/","og_locale":"en_US","og_type":"article","og_title":"Un gran negocio llamado inexistente S\u00edndrome de Alienaci\u00f3n Parental (iSAP) - DLVRADIO","og_description":"https:\/\/open.spotify.com\/episode\/4Kw3FwOtxDA9ItSdRRa6S5?si=Ti1BSIQwQvK5UBu1ebAxKA Nadie sabe, a menos que lo haya vivido, lo que supone que te arranquen a","og_url":"https:\/\/dlvradio.es\/en\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2021-02-07T21:52:58+00:00","og_image":[{"width":1511,"height":1511,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/02\/Un-gran-negocio-llamado-inexistente-Sindrome-de-Alienacion-Parental-iSAP.jpg","type":"image\/jpeg"}],"author":"DLV RADIO","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/"},"author":{"name":"DLV RADIO","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de"},"headline":"Un gran negocio llamado inexistente S\u00edndrome de Alienaci\u00f3n Parental (iSAP)","datePublished":"2021-02-07T21:52:58+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/"},"wordCount":178,"commentCount":0,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/02\/Un-gran-negocio-llamado-inexistente-Sindrome-de-Alienacion-Parental-iSAP.jpg","keywords":["actualidad","feminismo","leyes"],"articleSection":["Feminismo","Informativos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/","url":"https:\/\/dlvradio.es\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/","name":"Un gran negocio llamado inexistente S\u00edndrome de Alienaci\u00f3n Parental (iSAP) - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/02\/Un-gran-negocio-llamado-inexistente-Sindrome-de-Alienacion-Parental-iSAP.jpg","datePublished":"2021-02-07T21:52:58+00:00","description":"https:\/\/open.spotify.com\/episode\/4Kw3FwOtxDA9ItSdRRa6S5?si=Ti1BSIQwQvK5UBu1ebAxKA Nadie sabe, a menos que lo haya vivido, lo que supone que te arranquen a","breadcrumb":{"@id":"https:\/\/dlvradio.es\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/02\/Un-gran-negocio-llamado-inexistente-Sindrome-de-Alienacion-Parental-iSAP.jpg","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/02\/Un-gran-negocio-llamado-inexistente-Sindrome-de-Alienacion-Parental-iSAP.jpg","width":1511,"height":1511,"caption":"Un gran negocio llamado inexistente S\u00edndrome de Alienaci\u00f3n Parental (iSAP)"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/un-gran-negocio-llamado-inexistente-sindrome-de-alienacion-parental-isap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"Un gran negocio llamado inexistente S\u00edndrome de Alienaci\u00f3n Parental (iSAP)"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de","name":"DLV RADIO","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/70302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=70302"}],"version-history":[{"count":0,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/70302\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/70303"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=70302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=70302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=70302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}