{"id":70416,"date":"2021-03-20T18:56:02","date_gmt":"2021-03-20T17:56:02","guid":{"rendered":"https:\/\/dlvradio.es\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/"},"modified":"2021-03-20T18:56:02","modified_gmt":"2021-03-20T17:56:02","slug":"ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/","title":{"rendered":"Ecologistas en Acci\u00f3n demanda moratoria en las plantaciones de eucalipto en Espa\u00f1a"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft wp-image-6386 size-thumbnail\" src=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/03\/Ecologistas-en-Accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-Espana-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>La organizaci\u00f3n ecologista aplaude el anuncio del Gobierno gallego de la declaraci\u00f3n de una moratoria para la plantaci\u00f3n de eucaliptos y se\u00f1ala la importancia de que, por fin, un gobierno auton\u00f3mico reconozca el grave problema econ\u00f3mico y ambiental que provoca el monocultivo del eucalipto.<\/p>\n<ul>\n<li>Ecologistas en Acci\u00f3n se\u00f1ala que la moratoria es un primer paso fundamental para comenzar a revertir la situaci\u00f3n, pero que no tendr\u00e1 valor ninguno si no va aparejada de medidas espec\u00edficas de control y ordenaci\u00f3n.<\/li>\n<li>La organizaci\u00f3n ecologista invita al resto de comunidades aut\u00f3nomas afectadas por esta plaga invasora a declarar tambi\u00e9n la moratoria para impedir que se propague m\u00e1s este cultivo.<\/li>\n<\/ul>\n<p>Ecologistas en Acci\u00f3n recuerda que Galicia, Andaluc\u00eda y las comunidades de la cornisa cant\u00e1brica (Asturias, Cantabria y Euskadi) son los territorios que m\u00e1s sufren las consecuencias de los monocultivos de eucalipto. El eucalipto fue introducido a ra\u00edz de la creaci\u00f3n del Patrimonio Forestal del Estado, coincidiendo con el r\u00e9gimen de la dictadura franquista, con el objeto de abastecer de madera a las factor\u00edas de celulosa para la industria papelera.<\/p>\n<p>Andaluc\u00eda es una de las comunidades afectadas, pero de forma muy desigual en su territorio. Las plantaciones de esta especie ex\u00f3tica se concentran en Huelva, provincia en la que se ubicaba una de las f\u00e1bricas de la papelera espa\u00f1ola ENCE. Seg\u00fan datos oficiales de 2016, los eucaliptos ocupan 148.000 hect\u00e1reas en Huelva, 32.665 de ellas en espacios protegidos de alto valor ecol\u00f3gico: Red Natura 2000 y Red de Espacios Naturales Protegidos de Andaluc\u00eda. Actualmente los cultivos y los perniciosos aterrazamientos siguen adelante, haciendo un da\u00f1o especialmente en \u00e1reas como Parque natural Sierra de Aracena y Picos de Aroche, donde las empresas dedicadas al cultivo de eucalipto siguen plantando nuevamente m\u00e1s all\u00e1 de los tres turnos que se permiten, debido a la ambig\u00fcedad del instrumento de planificaci\u00f3n, donde caben las interpretaciones. La administraci\u00f3n ambiental andaluza justifica con ello las autorizaciones a empresas como Ibereucalipto o Ence.<\/p>\n<p>Las comunidades aut\u00f3nomas de la cornisa cant\u00e1brica tambi\u00e9n est\u00e1n afectadas en mayor o menor medida por esta plaga. En las \u00faltimas tres d\u00e9cadas la superficie cubierta por eucaliptos se ha multiplicado por cuatro en Euskadi debido a su mayor rentabilidad y ya cubre el 2,6% del territorio. Este territorio tambi\u00e9n sigue el mismo camino con una superficie ocupada ya de 21.500 hect\u00e1reas, principalmente localizadas en Bizkaia y en zonas costeras. Adem\u00e1s, se est\u00e1 viendo con preocupaci\u00f3n la tendencia de los propietarios privados de terrenos a reemplazar, para evitar la plaga de la banda marr\u00f3n, plantaciones de pino por eucalipto. Esto podr\u00eda suponer un gran aumento en pr\u00f3ximos a\u00f1os de la superficie ocupada.<\/p>\n<p>El propio Departamento de Medio Ambiente del gobierno aut\u00f3nomo vasco encarg\u00f3 un estudio a un equipo de expertos de la Universidad del Pa\u00eds Vasco-Euskal Herriko Unibertsitatea y de la Sociedad de Ciencias Aranzadi. La conclusi\u00f3n final de dicho estudio es que los eucaliptos tienen \u201cun efecto ambiental negativo, tanto en el Pa\u00eds Vasco como en el resto de la pen\u00ednsula\u201d. El informe indica adem\u00e1s que la expansi\u00f3n de las plantaciones de eucaliptos \u201cpuede ocasionar serios efectos ambientales\u201d tanto en los suelos y la hidrolog\u00eda como en la biodiversidad.<\/p>\n<p>Las plantaciones de eucalipto ocupan 40.000 hect\u00e1reas en Cantabria, el 11 % de toda su superficie forestal. El Tercer Inventario Forestal Nacional, elaborado para Cantabria en 2004, desvelaba que la superficie ocupada por los eucaliptales en la regi\u00f3n ascend\u00eda ya 46.200 hect\u00e1reas. Este dato, que otorga a los eucaliptos el t\u00edtulo de segunda especie forestal m\u00e1s extendida en el territorio c\u00e1ntabro, deja patente la realidad del tipo de bosque de esta comunidad y su pol\u00edtica forestal. Esta plaga se ha convertido en la modeladora del paisaje c\u00e1ntabro, sobre todo por debajo de los 400 metros de altitud como en el caso de la l\u00ednea de costa.<\/p>\n<p>Asturias no eludi\u00f3 esta plaga. Las plantaciones de eucaliptos ocupan ya casi 70.000 hect\u00e1reas y son la especie m\u00e1s presente en la masa forestal de esta regi\u00f3n, aunque su peso relativo es motivo de debate. El \u00faltimo inventario forestal nacional les atribuye menos peso del que calcula la Universidad de Oviedo a trav\u00e9s del Instituto de Recursos Naturales (Indurot). En todo caso, representan, como m\u00ednimo, cerca de la quinta parte de todos los \u00e1rboles que crecen entre la cordillera y el Cant\u00e1brico. Su expansi\u00f3n sigue a tal ritmo que en el 2018 ya se hab\u00eda superado la superficie que el plan forestal vigente calculaba que ocupar\u00edan en los a\u00f1os posteriores al 2050. Frente a esto cabe destacar iniciativas como la del ayuntamiento de Gij\u00f3n que hace unos meses anunci\u00f3 la tala de todos los eucaliptos presentes en suelo p\u00fablico municipal.<\/p>\n<p>En Galicia el Plan Forestal Gallego de 1992 establec\u00eda como umbral que, en el a\u00f1o 2032, las plantaciones de las especies de eucaliptos ocupar\u00edan 245.000 hect\u00e1reas. Seg\u00fan los \u00faltimos datos del Inventario Forestal de Especies Productivas \u2013realizado cada d\u00e9cada por el ministerio\u2013, en 2018 eran ya 300.500 hect\u00e1reas de monocultivo de eucalipto (englobando sobre todo dos especies Eucalyptus globulus y E. nitens) y otras 121.700 hect\u00e1reas en las que estas especies se encontraban presente de alg\u00fan modo. Es decir, casi el doble de las previstas para 2032. A la espera del nuevo inventario encargado por el Gobierno gallego, ya hay voces autorizadas que alertan de que la superficie ocupada por estas especies invasoras en Galicia puede alcanzar ya 600.000 hect\u00e1reas.<\/p>\n<p>Ecologistas Acci\u00f3n se congratula de que por fin se asuma por parte de un gobierno auton\u00f3mico esta insistente demanda de todo el ecologismo, pero prefiere esperar para realizar una valoraci\u00f3n hasta tener el texto de la ley. En este sentido la organizaci\u00f3n ecologista alerta de que la moratoria puede quedar en un anuncio bald\u00edo si no va acompa\u00f1ada de un reforzamiento de las medidas de control y vigilancia de las plantaciones ilegales, as\u00ed como del establecimiento de medidas sancionadoras coercitivas para las empresas del sector forestal que accedan a realizar nuevas plantaciones de eucalipto durante la moratoria.<\/p>\n<p>La organizaci\u00f3n ecologista entiende que si el primer paso es asegurar que la moratoria se aprueba con medios y recursos para ser aplicada, el segundo paso para revertir la situaci\u00f3n ser\u00eda revisar de oficio todas las plantaciones ilegales realizadas desde la aprobaci\u00f3n de la Ley de incendios 3\/2017 y de la Ley 7\/2012 de montes exigiendo el cumplimiento de lo establecido en dichas leyes.<\/p>\n<p>Asimismo, indica que el nuevo Plan Forestal, reci\u00e9n aprobado por el Gobierno gallego, fomenta el monocultivo y el aumento de especies pir\u00f3fitas e invasoras hasta alcanzar 1,4 millones de hect\u00e1reas de pinos y eucaliptos en 2040, y el aumento de 3 millones de m\u00b3 de talas anuales de madera de bajo valor a\u00f1adido hasta alcanzar los 12 millones de m\u00b3 de talas\/a\u00f1o. Un plan que propone aumentar a\u00fan m\u00e1s la superficie ocupada por el eucalipto E. nitens, pese a tener rebasado ya en m\u00e1s del doble las previsiones para 2030, y en detrimento de las masas forestales aut\u00f3ctonas que apenas sufrir\u00e1n incremento en los pr\u00f3ximos 20 a\u00f1os.<\/p>\n<p>Ecologistas en Acci\u00f3n entiende que una vez que el Gobierno gallego reconoce el grave problema econ\u00f3mico y ambiental del monocultivo del eucalipto, debe forzosamente derogar el Plan Forestal Gallego reci\u00e9n aprobado, ya que este no hace m\u00e1s que agravar la situaci\u00f3n actual. La organizaci\u00f3n ecologista indica que el Parlamento gallego deber\u00eda devolver el Plan Forestal Gallego al Consejo Forestal para realizar una nueva redacci\u00f3n id\u00f3nea a las necesidades del pa\u00eds y en la que puedan participar todas las organizaciones relacionadas con el monte y con el medio rural.<\/p>\n<p>Ecologistas en Acci\u00f3n recuerda que en el a\u00f1o 2017 el comit\u00e9 asesor cient\u00edfico del entonces ministerio de Agricultura, Pesca, Alimentaci\u00f3n y Medio Ambiente recomend\u00f3 la declaraci\u00f3n de Especie Ex\u00f3tica Invasora (EEI) para varias especies del g\u00e9nero Eucalyptus usadas por la industria agroforestal intensiva. Dicho dictamen cient\u00edfico, apoyado en diversos estudios realizados en Galicia y Portugal, deber\u00eda tenerse en cuenta para abordar la restauraci\u00f3n ecol\u00f3gica de las zonas afectadas por la invasi\u00f3n de estas especies y una profunda reconversi\u00f3n del sector. Para ello, las administraciones actuales afectadas deber\u00edan declarar a estas especies como EEI y actuar en consecuencia.<\/p>","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n ecologista aplaude el anuncio del Gobierno gallego de la declaraci\u00f3n de una moratoria para la plantaci\u00f3n de eucaliptos y se\u00f1ala la importancia de que, por fin, un gobierno auton\u00f3mico reconozca el grave problema econ\u00f3mico y ambiental que provoca el monocultivo del eucalipto. Ecologistas en Acci\u00f3n se\u00f1ala que la moratoria es un primer paso [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2465],"tags":[2478,2466],"class_list":["post-70416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informativos","tag-ecologia","tag-espana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecologistas en Acci\u00f3n demanda moratoria en las plantaciones de eucalipto en Espa\u00f1a - DLVRADIO<\/title>\n<meta name=\"description\" content=\"La organizaci\u00f3n ecologista aplaude el anuncio del Gobierno gallego de la declaraci\u00f3n de una moratoria para la plantaci\u00f3n de eucaliptos y se\u00f1ala la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecologistas en Acci\u00f3n demanda moratoria en las plantaciones de eucalipto en Espa\u00f1a - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"La organizaci\u00f3n ecologista aplaude el anuncio del Gobierno gallego de la declaraci\u00f3n de una moratoria para la plantaci\u00f3n de eucaliptos y se\u00f1ala la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-20T17:56:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/03\/Ecologistas-en-Accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-Espana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1511\" \/>\n\t<meta property=\"og:image:height\" content=\"1511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DLV RADIO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\\\/\"},\"author\":{\"name\":\"DLV RADIO\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\"},\"headline\":\"Ecologistas en Acci\u00f3n demanda moratoria en las plantaciones de eucalipto en Espa\u00f1a\",\"datePublished\":\"2021-03-20T17:56:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\\\/\"},\"wordCount\":1457,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Ecologistas-en-Accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-Espana.jpg\",\"keywords\":[\"ecolog\u00eda\",\"Espa\u00f1a\"],\"articleSection\":[\"Informativos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\\\/\",\"name\":\"Ecologistas en Acci\u00f3n demanda moratoria en las plantaciones de eucalipto en Espa\u00f1a - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Ecologistas-en-Accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-Espana.jpg\",\"datePublished\":\"2021-03-20T17:56:02+00:00\",\"description\":\"La organizaci\u00f3n ecologista aplaude el anuncio del Gobierno gallego de la declaraci\u00f3n de una moratoria para la plantaci\u00f3n de eucaliptos y se\u00f1ala la\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Ecologistas-en-Accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-Espana.jpg\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Ecologistas-en-Accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-Espana.jpg\",\"width\":1511,\"height\":1511,\"caption\":\"Ecologistas en Acci\u00f3n demanda moratoria en las plantaciones de eucalipto en Espa\u00f1a\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecologistas en Acci\u00f3n demanda moratoria en las plantaciones de eucalipto en Espa\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\",\"name\":\"DLV RADIO\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecologistas en Acci\u00f3n demanda moratoria en las plantaciones de eucalipto en Espa\u00f1a - DLVRADIO","description":"La organizaci\u00f3n ecologista aplaude el anuncio del Gobierno gallego de la declaraci\u00f3n de una moratoria para la plantaci\u00f3n de eucaliptos y se\u00f1ala la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/","og_locale":"en_US","og_type":"article","og_title":"Ecologistas en Acci\u00f3n demanda moratoria en las plantaciones de eucalipto en Espa\u00f1a - DLVRADIO","og_description":"La organizaci\u00f3n ecologista aplaude el anuncio del Gobierno gallego de la declaraci\u00f3n de una moratoria para la plantaci\u00f3n de eucaliptos y se\u00f1ala la","og_url":"https:\/\/dlvradio.es\/en\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2021-03-20T17:56:02+00:00","og_image":[{"width":1511,"height":1511,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/03\/Ecologistas-en-Accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-Espana.jpg","type":"image\/jpeg"}],"author":"DLV RADIO","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/"},"author":{"name":"DLV RADIO","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de"},"headline":"Ecologistas en Acci\u00f3n demanda moratoria en las plantaciones de eucalipto en Espa\u00f1a","datePublished":"2021-03-20T17:56:02+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/"},"wordCount":1457,"commentCount":0,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/03\/Ecologistas-en-Accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-Espana.jpg","keywords":["ecolog\u00eda","Espa\u00f1a"],"articleSection":["Informativos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/","url":"https:\/\/dlvradio.es\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/","name":"Ecologistas en Acci\u00f3n demanda moratoria en las plantaciones de eucalipto en Espa\u00f1a - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/03\/Ecologistas-en-Accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-Espana.jpg","datePublished":"2021-03-20T17:56:02+00:00","description":"La organizaci\u00f3n ecologista aplaude el anuncio del Gobierno gallego de la declaraci\u00f3n de una moratoria para la plantaci\u00f3n de eucaliptos y se\u00f1ala la","breadcrumb":{"@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/03\/Ecologistas-en-Accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-Espana.jpg","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/03\/Ecologistas-en-Accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-Espana.jpg","width":1511,"height":1511,"caption":"Ecologistas en Acci\u00f3n demanda moratoria en las plantaciones de eucalipto en Espa\u00f1a"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-demanda-moratoria-en-las-plantaciones-de-eucalipto-en-espana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"Ecologistas en Acci\u00f3n demanda moratoria en las plantaciones de eucalipto en Espa\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de","name":"DLV RADIO","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/70416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=70416"}],"version-history":[{"count":0,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/70416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/70417"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=70416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=70416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=70416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}