{"id":70574,"date":"2021-06-03T09:50:23","date_gmt":"2021-06-03T07:50:23","guid":{"rendered":"https:\/\/dlvradio.es\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/"},"modified":"2021-06-03T09:50:23","modified_gmt":"2021-06-03T07:50:23","slug":"ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/","title":{"rendered":"Ecologistas en Acci\u00f3n presenta &#8216;Eres el peque\u00f1o detalle que lo cambia todo&#8217;"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft wp-image-6680 size-thumbnail\" src=\"https:\/\/dlvradio.es\/copia\/wp-content\/uploads\/2021\/04\/ecoloverdnatu-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>Os dejamos la nota de prensa de Ecologistas en Acci\u00f3n:<\/p>\n<p>Ecol\u00f3gica Aplastante, la primera <a href=\"https:\/\/www.ecologistasenaccion.org\/29132\/presentan-la-campana-ecologica-aplastante\/\">gran campa\u00f1a<\/a> de captaci\u00f3n de personas socias y voluntarias de Ecologistas en Acci\u00f3n, pasa a su segunda fase.<\/p>\n<ul>\n<li>&#8216;Eres el peque\u00f1o detalle que lo cambia todo&#8217; est\u00e1 basada en una idea de Viernes, agencia creativa especializada en ecologismo, sostenibilidad y justicia social, con la que Ecologistas en Acci\u00f3n trabaj\u00f3 para dise\u00f1ar Ecol\u00f3gica Aplastante.<\/li>\n<li>En esta segunda fase de la campa\u00f1a, han sido los grupos y federaciones de Ecologistas en Acci\u00f3n quienes se han encargado de dise\u00f1ar y preparar todos los materiales.<\/li>\n<li>&#8216;Eres el peque\u00f1o detalle que lo cambia todo&#8217; est\u00e1 centrado en las luchas locales y territoriales de la organizaci\u00f3n ecologista.<\/li>\n<\/ul>\n<p>En diciembre de 2020 Ecologistas en Acci\u00f3n lanz\u00f3 su primera gran campa\u00f1a de captaci\u00f3n de personas socias y voluntarias en sus 22 a\u00f1os de trayectoria.<\/p>\n<p>La campa\u00f1a est\u00e1 dividida en dos fases: Ecol\u00f3gica Aplastante y Eres el peque\u00f1o detalle que lo cambia todo. La primera es m\u00e1s gen\u00e9rica, con mensajes amplios y sencillos, con un ritmo y una po\u00e9tica que la organizaci\u00f3n ecologista trabaj\u00f3 con Viernes, agencia creativa especializada en ecologismo, sostenibilidad y justicia social.<\/p>\n<p>Ecol\u00f3gica Aplastante parte de la ra\u00edz del problema de la crisis ecol\u00f3gica actual: el modelo econ\u00f3mico dominante basado en el abuso de los recursos naturales, el beneficio inmediato y la desigualdad. La campa\u00f1a expone que el crecimiento ilimitado en un planeta finito no es viable, y sostiene que el hecho de que una especie entre millones se considere independiente, superior y poseedora del resto de las formas de vida que la rodean, es irracional e injusto.<\/p>\n<p>Por su parte, &#8216;Eres el peque\u00f1o detalle que lo cambia todo&#8217; aterriza toda una serie de problem\u00e1ticas vinculadas a las luchas locales de Ecologistas en Acci\u00f3n y pasa a ser una fase eminentemente territorial, donde ya no se lanzan mensajes gen\u00e9ricos sino muy concretos, centrados en la actividad de la organizaci\u00f3n ecologista en la defensa del territorio. Este paraguas conceptual ofrece una mirada que va de lo local a lo global, con un sentido de movimiento social que cree sentido de pertenencia. El protagonismo ya no lo tienen im\u00e1genes de personas indeterminadas, sino activistas de Ecologistas en Acci\u00f3n.<\/p>\n<p>Ecologistas en Acci\u00f3n ajusta el foco para colocarlo en sus luchas locales y territoriales, base del trabajo de la confederaci\u00f3n ecologista desde que se fundara en diciembre de 1998. Por ello, en esta fase han sido los numerosos grupos y federaciones de la organizaci\u00f3n ecologista los que se han encargado de dise\u00f1ar y preparar todos los carteles.<\/p>\n<p>Con estos materiales, Ecologistas en Acci\u00f3n pretende dar a conocer su trabajo en la defensa del territorio con el objetivo de sumar activistas y socias: desde el cierre de la incineradora de la cementera en C\u00f3rdoba hasta la defensa de las reservas fluviales en Le\u00f3n mediante la prohibici\u00f3n de las embotelladoras en Pobladura de la Sierra o la paralizaci\u00f3n de la ampliaci\u00f3n del puerto de Valencia, considerada la mayor amenaza ambiental que viven en el Pa\u00eds Valenci\u00e0.<\/p>\n<p>De la defensa de Madrid Central como herramienta para la mejora de la calidad del aire a la protecci\u00f3n de las dunas del litoral galego o la conservaci\u00f3n de la biodiversidad canaria, como fuente de vida y forma para luchar contra la emergencia clim\u00e1tica. De la reivindicaci\u00f3n de la renaturalizaci\u00f3n de los r\u00edos Bes\u00f2s y Francol\u00ed en Catalunya a la construcci\u00f3n del humedal La Degollada en La Rioja, pasando por la cr\u00edtica a la gesti\u00f3n de los residuos para que no haya ni un Zaldibar m\u00e1s a la iniciativa de llevar al entorno aragon\u00e9s de Pinzana una ambiciosa propuesta de educaci\u00f3n ambiental.<\/p>\n<p>Estos son solo algunos ejemplos de los muchos que forman parte del d\u00eda a d\u00eda de Ecologistas en Acci\u00f3n, la organizaci\u00f3n ecologista con la vertebraci\u00f3n territorial m\u00e1s s\u00f3lida del Estado espa\u00f1ol. Una red compuesta, tambi\u00e9n, por peque\u00f1os detalles que lo cambian todo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Os dejamos la nota de prensa de Ecologistas en Acci\u00f3n: Ecol\u00f3gica Aplastante, la primera gran campa\u00f1a de captaci\u00f3n de personas socias y voluntarias de Ecologistas en Acci\u00f3n, pasa a su segunda fase. &#8216;Eres el peque\u00f1o detalle que lo cambia todo&#8217; est\u00e1 basada en una idea de Viernes, agencia creativa especializada en ecologismo, sostenibilidad y justicia [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70490,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2465],"tags":[2478],"class_list":["post-70574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informativos","tag-ecologia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecologistas en Acci\u00f3n presenta &#039;Eres el peque\u00f1o detalle que lo cambia todo&#039; - DLVRADIO<\/title>\n<meta name=\"description\" content=\"Os dejamos la nota de prensa de Ecologistas en Acci\u00f3n: Ecol\u00f3gica Aplastante, la primera gran campa\u00f1a de captaci\u00f3n de personas socias y voluntarias de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecologistas en Acci\u00f3n presenta &#039;Eres el peque\u00f1o detalle que lo cambia todo&#039; - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"Os dejamos la nota de prensa de Ecologistas en Acci\u00f3n: Ecol\u00f3gica Aplastante, la primera gran campa\u00f1a de captaci\u00f3n de personas socias y voluntarias de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-03T07:50:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/04\/ecoloverdnatu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1511\" \/>\n\t<meta property=\"og:image:height\" content=\"1511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DLV RADIO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\\\/\"},\"author\":{\"name\":\"DLV RADIO\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\"},\"headline\":\"Ecologistas en Acci\u00f3n presenta &#8216;Eres el peque\u00f1o detalle que lo cambia todo&#8217;\",\"datePublished\":\"2021-06-03T07:50:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\\\/\"},\"wordCount\":724,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/ecoloverdnatu.jpg\",\"keywords\":[\"ecolog\u00eda\"],\"articleSection\":[\"Informativos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\\\/\",\"name\":\"Ecologistas en Acci\u00f3n presenta 'Eres el peque\u00f1o detalle que lo cambia todo' - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/ecoloverdnatu.jpg\",\"datePublished\":\"2021-06-03T07:50:23+00:00\",\"description\":\"Os dejamos la nota de prensa de Ecologistas en Acci\u00f3n: Ecol\u00f3gica Aplastante, la primera gran campa\u00f1a de captaci\u00f3n de personas socias y voluntarias de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/ecoloverdnatu.jpg\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/ecoloverdnatu.jpg\",\"width\":1511,\"height\":1511,\"caption\":\"ecoloverdnatu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecologistas en Acci\u00f3n presenta &#8216;Eres el peque\u00f1o detalle que lo cambia todo&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\",\"name\":\"DLV RADIO\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecologistas en Acci\u00f3n presenta 'Eres el peque\u00f1o detalle que lo cambia todo' - DLVRADIO","description":"Os dejamos la nota de prensa de Ecologistas en Acci\u00f3n: Ecol\u00f3gica Aplastante, la primera gran campa\u00f1a de captaci\u00f3n de personas socias y voluntarias de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/","og_locale":"en_US","og_type":"article","og_title":"Ecologistas en Acci\u00f3n presenta 'Eres el peque\u00f1o detalle que lo cambia todo' - DLVRADIO","og_description":"Os dejamos la nota de prensa de Ecologistas en Acci\u00f3n: Ecol\u00f3gica Aplastante, la primera gran campa\u00f1a de captaci\u00f3n de personas socias y voluntarias de","og_url":"https:\/\/dlvradio.es\/en\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2021-06-03T07:50:23+00:00","og_image":[{"width":1511,"height":1511,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/04\/ecoloverdnatu.jpg","type":"image\/jpeg"}],"author":"DLV RADIO","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/"},"author":{"name":"DLV RADIO","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de"},"headline":"Ecologistas en Acci\u00f3n presenta &#8216;Eres el peque\u00f1o detalle que lo cambia todo&#8217;","datePublished":"2021-06-03T07:50:23+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/"},"wordCount":724,"commentCount":0,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/04\/ecoloverdnatu.jpg","keywords":["ecolog\u00eda"],"articleSection":["Informativos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/","url":"https:\/\/dlvradio.es\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/","name":"Ecologistas en Acci\u00f3n presenta 'Eres el peque\u00f1o detalle que lo cambia todo' - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/04\/ecoloverdnatu.jpg","datePublished":"2021-06-03T07:50:23+00:00","description":"Os dejamos la nota de prensa de Ecologistas en Acci\u00f3n: Ecol\u00f3gica Aplastante, la primera gran campa\u00f1a de captaci\u00f3n de personas socias y voluntarias de","breadcrumb":{"@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/04\/ecoloverdnatu.jpg","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/04\/ecoloverdnatu.jpg","width":1511,"height":1511,"caption":"ecoloverdnatu"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/ecologistas-en-accion-presenta-eres-el-pequeno-detalle-que-lo-cambia-todo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"Ecologistas en Acci\u00f3n presenta &#8216;Eres el peque\u00f1o detalle que lo cambia todo&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de","name":"DLV RADIO","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/70574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=70574"}],"version-history":[{"count":0,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/70574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/70490"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=70574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=70574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=70574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}