{"id":70579,"date":"2021-06-05T18:52:26","date_gmt":"2021-06-05T16:52:26","guid":{"rendered":"https:\/\/dlvradio.es\/el-decreto-nuestro-de-cada-dia-56\/"},"modified":"2021-06-05T18:52:26","modified_gmt":"2021-06-05T16:52:26","slug":"el-decreto-nuestro-de-cada-dia-56","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/el-decreto-nuestro-de-cada-dia-56\/","title":{"rendered":"El decreto nuestro de cada d\u00eda, 56"},"content":{"rendered":"<iframe id='audio_71002871' frameborder='0' allowfullscreen='' scrolling='no' height='200' style='width:100%;' src='https:\/\/www.ivoox.com\/player_ej_71002871_6_1.html'><\/iframe>\n\n\n<p><img decoding=\"async\" class=\"alignleft wp-image-6973\" src=\"https:\/\/dlvradio.es\/copia\/wp-content\/uploads\/2021\/06\/El-decreto-nuestro-de-cada-dia-56-150x150.jpg\" alt=\"\" width=\"130\" height=\"130\" \/>Como cada semana comentamos los datos del covid19 y la vacunaci\u00f3n en Espa\u00f1a. Repasamos la actualidad pol\u00edtica y social de Espa\u00f1a. Los datos del covid, vacunaci\u00f3n, desescalada por parte del Gobierno y de las diferentes comunidades aut\u00f3nomas. Lo presos del pr\u00f2ces y su liberaci\u00f3n. Los problemas de los trabajadores de Nissan, nos lo conto Dani de primera mano como trabajador en la planta de Barcelona. Esta semana nos acompa\u00f1an: N\u00faria Gonz\u00e1lez, Carlos Hidalgo, Emma Lebon, Dani Gallego y Gerardo Su\u00e1rez.<\/p>\n<p><iframe title=\"El decreto nuestro de cada d\u00eda, 56\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/_SmfSfzPAvw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Como cada semana comentamos los datos del covid19 y la vacunaci\u00f3n en Espa\u00f1a. Repasamos la actualidad pol\u00edtica y social de Espa\u00f1a. Los datos del covid, vacunaci\u00f3n, desescalada por parte del Gobierno y de las diferentes comunidades aut\u00f3nomas. Lo presos del pr\u00f2ces y su liberaci\u00f3n. Los problemas de los trabajadores de Nissan, nos lo conto Dani [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2766],"tags":[2530,2546],"class_list":["post-70579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-decreto","tag-actualidad","tag-pandemia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El decreto nuestro de cada d\u00eda, 56 - DLVRADIO<\/title>\n<meta name=\"description\" content=\"Como cada semana comentamos los datos del covid19 y la vacunaci\u00f3n en Espa\u00f1a. Repasamos la actualidad pol\u00edtica y social de Espa\u00f1a. Los datos del covid,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/el-decreto-nuestro-de-cada-dia-56\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El decreto nuestro de cada d\u00eda, 56 - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"Como cada semana comentamos los datos del covid19 y la vacunaci\u00f3n en Espa\u00f1a. Repasamos la actualidad pol\u00edtica y social de Espa\u00f1a. Los datos del covid,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/el-decreto-nuestro-de-cada-dia-56\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-05T16:52:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/06\/El-decreto-nuestro-de-cada-dia-56.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1511\" \/>\n\t<meta property=\"og:image:height\" content=\"1511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DLV RADIO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-decreto-nuestro-de-cada-dia-56\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-decreto-nuestro-de-cada-dia-56\\\/\"},\"author\":{\"name\":\"DLV RADIO\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\"},\"headline\":\"El decreto nuestro de cada d\u00eda, 56\",\"datePublished\":\"2021-06-05T16:52:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-decreto-nuestro-de-cada-dia-56\\\/\"},\"wordCount\":105,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-decreto-nuestro-de-cada-dia-56\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/El-decreto-nuestro-de-cada-dia-56.jpg\",\"keywords\":[\"actualidad\",\"pandemia\"],\"articleSection\":[\"El Decreto\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-decreto-nuestro-de-cada-dia-56\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/el-decreto-nuestro-de-cada-dia-56\\\/\",\"name\":\"El decreto nuestro de cada d\u00eda, 56 - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-decreto-nuestro-de-cada-dia-56\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-decreto-nuestro-de-cada-dia-56\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/El-decreto-nuestro-de-cada-dia-56.jpg\",\"datePublished\":\"2021-06-05T16:52:26+00:00\",\"description\":\"Como cada semana comentamos los datos del covid19 y la vacunaci\u00f3n en Espa\u00f1a. Repasamos la actualidad pol\u00edtica y social de Espa\u00f1a. Los datos del covid,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-decreto-nuestro-de-cada-dia-56\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/el-decreto-nuestro-de-cada-dia-56\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-decreto-nuestro-de-cada-dia-56\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/El-decreto-nuestro-de-cada-dia-56.jpg\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/El-decreto-nuestro-de-cada-dia-56.jpg\",\"width\":1511,\"height\":1511,\"caption\":\"El decreto nuestro de cada d\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-decreto-nuestro-de-cada-dia-56\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El decreto nuestro de cada d\u00eda, 56\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\",\"name\":\"DLV RADIO\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El decreto nuestro de cada d\u00eda, 56 - DLVRADIO","description":"Como cada semana comentamos los datos del covid19 y la vacunaci\u00f3n en Espa\u00f1a. Repasamos la actualidad pol\u00edtica y social de Espa\u00f1a. Los datos del covid,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/el-decreto-nuestro-de-cada-dia-56\/","og_locale":"en_US","og_type":"article","og_title":"El decreto nuestro de cada d\u00eda, 56 - DLVRADIO","og_description":"Como cada semana comentamos los datos del covid19 y la vacunaci\u00f3n en Espa\u00f1a. Repasamos la actualidad pol\u00edtica y social de Espa\u00f1a. Los datos del covid,","og_url":"https:\/\/dlvradio.es\/en\/el-decreto-nuestro-de-cada-dia-56\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2021-06-05T16:52:26+00:00","og_image":[{"width":1511,"height":1511,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/06\/El-decreto-nuestro-de-cada-dia-56.jpg","type":"image\/jpeg"}],"author":"DLV RADIO","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/el-decreto-nuestro-de-cada-dia-56\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/el-decreto-nuestro-de-cada-dia-56\/"},"author":{"name":"DLV RADIO","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de"},"headline":"El decreto nuestro de cada d\u00eda, 56","datePublished":"2021-06-05T16:52:26+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/el-decreto-nuestro-de-cada-dia-56\/"},"wordCount":105,"commentCount":0,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/el-decreto-nuestro-de-cada-dia-56\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/06\/El-decreto-nuestro-de-cada-dia-56.jpg","keywords":["actualidad","pandemia"],"articleSection":["El Decreto"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/el-decreto-nuestro-de-cada-dia-56\/","url":"https:\/\/dlvradio.es\/el-decreto-nuestro-de-cada-dia-56\/","name":"El decreto nuestro de cada d\u00eda, 56 - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/el-decreto-nuestro-de-cada-dia-56\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/el-decreto-nuestro-de-cada-dia-56\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/06\/El-decreto-nuestro-de-cada-dia-56.jpg","datePublished":"2021-06-05T16:52:26+00:00","description":"Como cada semana comentamos los datos del covid19 y la vacunaci\u00f3n en Espa\u00f1a. Repasamos la actualidad pol\u00edtica y social de Espa\u00f1a. Los datos del covid,","breadcrumb":{"@id":"https:\/\/dlvradio.es\/el-decreto-nuestro-de-cada-dia-56\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/el-decreto-nuestro-de-cada-dia-56\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/el-decreto-nuestro-de-cada-dia-56\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/06\/El-decreto-nuestro-de-cada-dia-56.jpg","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/06\/El-decreto-nuestro-de-cada-dia-56.jpg","width":1511,"height":1511,"caption":"El decreto nuestro de cada d\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/el-decreto-nuestro-de-cada-dia-56\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"El decreto nuestro de cada d\u00eda, 56"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de","name":"DLV RADIO","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/70579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=70579"}],"version-history":[{"count":0,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/70579\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/70580"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=70579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=70579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=70579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}