{"id":70582,"date":"2021-06-06T19:28:35","date_gmt":"2021-06-06T17:28:35","guid":{"rendered":"https:\/\/dlvradio.es\/arras-competicion-en-dlvradio-90\/"},"modified":"2021-06-06T19:28:35","modified_gmt":"2021-06-06T17:28:35","slug":"arras-competicion-en-dlvradio-90","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/arras-competicion-en-dlvradio-90\/","title":{"rendered":"Arras competici\u00f3n en DLVRADIO, 90"},"content":{"rendered":"<iframe id='audio_71026075' frameborder='0' allowfullscreen='' scrolling='no' height='200' style='width:100%;' src='https:\/\/www.ivoox.com\/player_ej_71026075_6_1.html'><\/iframe>\n\n\n<p><img decoding=\"async\" class=\"alignleft wp-image-6459 size-thumbnail\" src=\"https:\/\/dlvradio.es\/copia\/wp-content\/uploads\/2021\/03\/Arras-portada-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>Esta semana en el programa de Arras competici\u00f3n, comenzamos con las noticias de la mano de Xevi Mart\u00ednez desde el rallye s\u00f3lo GT TURBO en directo nos trasladamos hasta el Rallye Villa de Llanes de hist\u00f3rico donde nuestro compa\u00f1ero Fernando Galguera desde el tramo la Garita nos trajo lo \u00faltimo de vuelta volvimos a Cantabria para hablar con el piloto y organizador \u00d3scar Gonz\u00e1lez en directo desde el rallye solo GT TURBO y para terminar hablamos con el piloto Bombi Gazquez un preparador de coches de rallye y un crak en tik tok. Ya sab\u00e9is que ten\u00e9is #arrascompeticion todos los domingos a las 13:00 h. en www.dlvradio.es y en nuestras redes sociales. Espero que os guste y muchas gracias por seguirnos cada semana, saludos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Esta semana en el programa de Arras competici\u00f3n, comenzamos con las noticias de la mano de Xevi Mart\u00ednez desde el rallye s\u00f3lo GT TURBO en directo nos trasladamos hasta el Rallye Villa de Llanes de hist\u00f3rico donde nuestro compa\u00f1ero Fernando Galguera desde el tramo la Garita nos trajo lo \u00faltimo de vuelta volvimos a Cantabria [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70441,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2480],"tags":[2495,2473],"class_list":["post-70582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-entrevistas","tag-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arras competici\u00f3n en DLVRADIO, 90 - DLVRADIO<\/title>\n<meta name=\"description\" content=\"Esta semana en el programa de Arras competici\u00f3n, comenzamos con las noticias de la mano de Xevi Mart\u00ednez desde el rallye s\u00f3lo GT TURBO en directo nos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/arras-competicion-en-dlvradio-90\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arras competici\u00f3n en DLVRADIO, 90 - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"Esta semana en el programa de Arras competici\u00f3n, comenzamos con las noticias de la mano de Xevi Mart\u00ednez desde el rallye s\u00f3lo GT TURBO en directo nos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/arras-competicion-en-dlvradio-90\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-06T17:28:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/03\/Arras-portada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1511\" \/>\n\t<meta property=\"og:image:height\" content=\"1511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DLV RADIO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/arras-competicion-en-dlvradio-90\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/arras-competicion-en-dlvradio-90\\\/\"},\"author\":{\"name\":\"DLV RADIO\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\"},\"headline\":\"Arras competici\u00f3n en DLVRADIO, 90\",\"datePublished\":\"2021-06-06T17:28:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/arras-competicion-en-dlvradio-90\\\/\"},\"wordCount\":138,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/arras-competicion-en-dlvradio-90\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Arras-portada.jpg\",\"keywords\":[\"Entrevistas\",\"noticias\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/arras-competicion-en-dlvradio-90\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/arras-competicion-en-dlvradio-90\\\/\",\"name\":\"Arras competici\u00f3n en DLVRADIO, 90 - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/arras-competicion-en-dlvradio-90\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/arras-competicion-en-dlvradio-90\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Arras-portada.jpg\",\"datePublished\":\"2021-06-06T17:28:35+00:00\",\"description\":\"Esta semana en el programa de Arras competici\u00f3n, comenzamos con las noticias de la mano de Xevi Mart\u00ednez desde el rallye s\u00f3lo GT TURBO en directo nos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/arras-competicion-en-dlvradio-90\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/arras-competicion-en-dlvradio-90\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/arras-competicion-en-dlvradio-90\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Arras-portada.jpg\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Arras-portada.jpg\",\"width\":1511,\"height\":1511,\"caption\":\"Arras portada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/arras-competicion-en-dlvradio-90\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arras competici\u00f3n en DLVRADIO, 90\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\",\"name\":\"DLV RADIO\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arras competici\u00f3n en DLVRADIO, 90 - DLVRADIO","description":"Esta semana en el programa de Arras competici\u00f3n, comenzamos con las noticias de la mano de Xevi Mart\u00ednez desde el rallye s\u00f3lo GT TURBO en directo nos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/arras-competicion-en-dlvradio-90\/","og_locale":"en_US","og_type":"article","og_title":"Arras competici\u00f3n en DLVRADIO, 90 - DLVRADIO","og_description":"Esta semana en el programa de Arras competici\u00f3n, comenzamos con las noticias de la mano de Xevi Mart\u00ednez desde el rallye s\u00f3lo GT TURBO en directo nos","og_url":"https:\/\/dlvradio.es\/en\/arras-competicion-en-dlvradio-90\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2021-06-06T17:28:35+00:00","og_image":[{"width":1511,"height":1511,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/03\/Arras-portada.jpg","type":"image\/jpeg"}],"author":"DLV RADIO","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/arras-competicion-en-dlvradio-90\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/arras-competicion-en-dlvradio-90\/"},"author":{"name":"DLV RADIO","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de"},"headline":"Arras competici\u00f3n en DLVRADIO, 90","datePublished":"2021-06-06T17:28:35+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/arras-competicion-en-dlvradio-90\/"},"wordCount":138,"commentCount":0,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/arras-competicion-en-dlvradio-90\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/03\/Arras-portada.jpg","keywords":["Entrevistas","noticias"],"articleSection":["Deportes"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/arras-competicion-en-dlvradio-90\/","url":"https:\/\/dlvradio.es\/arras-competicion-en-dlvradio-90\/","name":"Arras competici\u00f3n en DLVRADIO, 90 - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/arras-competicion-en-dlvradio-90\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/arras-competicion-en-dlvradio-90\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/03\/Arras-portada.jpg","datePublished":"2021-06-06T17:28:35+00:00","description":"Esta semana en el programa de Arras competici\u00f3n, comenzamos con las noticias de la mano de Xevi Mart\u00ednez desde el rallye s\u00f3lo GT TURBO en directo nos","breadcrumb":{"@id":"https:\/\/dlvradio.es\/arras-competicion-en-dlvradio-90\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/arras-competicion-en-dlvradio-90\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/arras-competicion-en-dlvradio-90\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/03\/Arras-portada.jpg","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/03\/Arras-portada.jpg","width":1511,"height":1511,"caption":"Arras portada"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/arras-competicion-en-dlvradio-90\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"Arras competici\u00f3n en DLVRADIO, 90"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de","name":"DLV RADIO","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/70582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=70582"}],"version-history":[{"count":0,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/70582\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/70441"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=70582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=70582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=70582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}