{"id":71632,"date":"2022-11-13T12:43:20","date_gmt":"2022-11-13T11:43:20","guid":{"rendered":"https:\/\/dlvradio.es\/en-lescola-con-nuria-139\/"},"modified":"2022-11-13T12:43:20","modified_gmt":"2022-11-13T11:43:20","slug":"en-lescola-con-nuria-139","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/en-lescola-con-nuria-139\/","title":{"rendered":"En L&#8217;Escola con N\u00faria, 139"},"content":{"rendered":"<iframe src=\"https:\/\/www.ivoox.com\/player_ej_96301911_6_1.html?c1=0ebeb7\" width=\"100%\" height=\"200\" frameborder=\"0\" allowfullscreen=\"\" scrolling=\"no\" loading=\"lazy\"><\/iframe>\n\n\n<p><img decoding=\"async\" class=\"alignleft wp-image-7754 size-thumbnail\" src=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>Aqu\u00ed estamos una semana m\u00e1s con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria en nuestro programa ya 139. Esta semana hablamos de periodismo y de la culturawoke con Cristina Prieto. \u00bfQu\u00e9 est\u00e1 pasando con los bitcoins? La crisis de los bitcoins arrastra a miles de personas en el mundo entero incluso alg\u00fan pa\u00eds puede tener serios problemas, os lo contamos todo al respecto. El dichoso MundialQatar2022 se jugar\u00e1 en un pa\u00eds sin Derechos Humanos, y con cientos de muertos en su construcci\u00f3n, pero parece ser que a l mundo no le interesa mucho esos temas, por desgracia. Un tratamiento dig\u00e1moslo peculiar con drogas psicod\u00e9licas contra la depresi\u00f3n, que hay detr\u00e1s de ello. Cerramos con El Rata de la semana, en esta ocasi\u00f3n contra todos aquellos que quieren liquidar la Sanidad P\u00fablica en Espa\u00f1a y sus diferentes comunidades aut\u00f3nomas.<\/p>","protected":false},"excerpt":{"rendered":"<p>Aqu\u00ed estamos una semana m\u00e1s con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria en nuestro programa ya 139. Esta semana hablamos de periodismo y de la culturawoke con Cristina Prieto. \u00bfQu\u00e9 est\u00e1 pasando con los bitcoins? La crisis de los bitcoins arrastra a miles de personas en el mundo entero incluso alg\u00fan pa\u00eds puede tener [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2560],"tags":[2530,2495,2643],"class_list":["post-71632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-lescola-con-nuria","tag-actualidad","tag-entrevistas","tag-magazin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En L&#039;Escola con N\u00faria, 139 - DLVRADIO<\/title>\n<meta name=\"description\" content=\"Aqu\u00ed estamos una semana m\u00e1s con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria en nuestro programa ya 139. Esta semana hablamos de periodismo y de la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/en-lescola-con-nuria-139\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En L&#039;Escola con N\u00faria, 139 - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"Aqu\u00ed estamos una semana m\u00e1s con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria en nuestro programa ya 139. Esta semana hablamos de periodismo y de la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/en-lescola-con-nuria-139\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-13T11:43:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1511\" \/>\n\t<meta property=\"og:image:height\" content=\"1511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DLV RADIO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-139\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-139\\\/\"},\"author\":{\"name\":\"DLV RADIO\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\"},\"headline\":\"En L&#8217;Escola con N\u00faria, 139\",\"datePublished\":\"2022-11-13T11:43:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-139\\\/\"},\"wordCount\":159,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-139\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/LEscola-nu.jpg\",\"keywords\":[\"actualidad\",\"Entrevistas\",\"magaz\u00edn\"],\"articleSection\":[\"En L'Escola con N\u00faria\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-139\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-139\\\/\",\"name\":\"En L'Escola con N\u00faria, 139 - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-139\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-139\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/LEscola-nu.jpg\",\"datePublished\":\"2022-11-13T11:43:20+00:00\",\"description\":\"Aqu\u00ed estamos una semana m\u00e1s con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria en nuestro programa ya 139. Esta semana hablamos de periodismo y de la\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-139\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-139\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-139\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/LEscola-nu.jpg\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/LEscola-nu.jpg\",\"width\":1511,\"height\":1511,\"caption\":\"L'Escola nu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-139\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En L&#8217;Escola con N\u00faria, 139\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\",\"name\":\"DLV RADIO\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En L'Escola con N\u00faria, 139 - DLVRADIO","description":"Aqu\u00ed estamos una semana m\u00e1s con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria en nuestro programa ya 139. Esta semana hablamos de periodismo y de la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/en-lescola-con-nuria-139\/","og_locale":"en_US","og_type":"article","og_title":"En L'Escola con N\u00faria, 139 - DLVRADIO","og_description":"Aqu\u00ed estamos una semana m\u00e1s con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria en nuestro programa ya 139. Esta semana hablamos de periodismo y de la","og_url":"https:\/\/dlvradio.es\/en\/en-lescola-con-nuria-139\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2022-11-13T11:43:20+00:00","og_image":[{"width":1511,"height":1511,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg","type":"image\/jpeg"}],"author":"DLV RADIO","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-139\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-139\/"},"author":{"name":"DLV RADIO","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de"},"headline":"En L&#8217;Escola con N\u00faria, 139","datePublished":"2022-11-13T11:43:20+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-139\/"},"wordCount":159,"commentCount":0,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-139\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg","keywords":["actualidad","Entrevistas","magaz\u00edn"],"articleSection":["En L'Escola con N\u00faria"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-139\/","url":"https:\/\/dlvradio.es\/en-lescola-con-nuria-139\/","name":"En L'Escola con N\u00faria, 139 - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-139\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-139\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg","datePublished":"2022-11-13T11:43:20+00:00","description":"Aqu\u00ed estamos una semana m\u00e1s con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria en nuestro programa ya 139. Esta semana hablamos de periodismo y de la","breadcrumb":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-139\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/en-lescola-con-nuria-139\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-139\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg","width":1511,"height":1511,"caption":"L'Escola nu"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-139\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"En L&#8217;Escola con N\u00faria, 139"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de","name":"DLV RADIO","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/71632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=71632"}],"version-history":[{"count":0,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/71632\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/70815"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=71632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=71632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=71632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}