{"id":71683,"date":"2022-12-15T11:37:06","date_gmt":"2022-12-15T10:37:06","guid":{"rendered":"https:\/\/dlvradio.es\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/"},"modified":"2022-12-15T11:37:06","modified_gmt":"2022-12-15T10:37:06","slug":"el-2023-tampoco-vera-el-fin-de-la-sobrepesca","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/","title":{"rendered":"<strong>El 2023 tampoco ver\u00e1 el fin de la sobrepesca<\/strong>"},"content":{"rendered":"<h6><strong><img decoding=\"async\" class=\"alignleft wp-image-10693 size-thumbnail\" src=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2022\/12\/El-2023-tampoco-vera-el-fin-de-la-sobrepesca-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>El 2023 tampoco ver\u00e1 el fin de la sobrepesca<\/strong><\/h6>\n<ul>\n<li>Tras dos d\u00edas de negociaciones a puerta cerrada en el Consejo de la UE, se han establecido los l\u00edmites de capturas para las poblaciones de peces del Atl\u00e1ntico nororiental, incluyendo las especies del fondo, y el futuro de las poblaciones del Mediterr\u00e1neo para el 2023.<\/li>\n<li>Ecologistas en Acci\u00f3n ha valorado los resultados como decepcionantes: aunque algunas especies se hayan recuperado (como el gallo o la merluza del sur), los TAC inciden en la sobrepesca de otras especies que est\u00e1n en situaciones de mayor vulnerabilidad, como la cigala o el besugo.<\/li>\n<li>Los grandes protagonistas del debate \u2013la anguila europea y la reducci\u00f3n de esfuerzo en el Mediterr\u00e1neo\u2013 han progresado, aunque no al ritmo necesario para acabar con la sobrepesca.<\/li>\n<\/ul>\n<p>Ministras y ministros de Pesca de la UE han terminado las negociaciones para establecer los l\u00edmites de captura (TAC) para las poblaciones de peces del Atl\u00e1ntico nororiental en 2023 que, en esta ocasi\u00f3n, tambi\u00e9n incluyen los TAC para las especies de aguas profundas. Estos TAC marcar\u00e1n la cantidad de peces que puede pescar cada Estado miembro el a\u00f1o que viene y tambi\u00e9n para 2024 en el caso de las especies de aguas profundas. Adem\u00e1s, se han vuelto a negociar las medidas que se aplicar\u00e1n en el Mediterr\u00e1neo para combatir la grave sobrepesca que sufre este mar.<\/p>\n<p>Ecologistas en Acci\u00f3n ha celebrado que este a\u00f1o algunas especies de inter\u00e9s pesquero\u00a0 para el Estado espa\u00f1ol \u2013como el gallo, el rape, la poblaci\u00f3n de jurel del sur o chicharro, la merluza del sur y la bacaladilla\u2013 presenten biomasas crecientes, por lo que la recomendaci\u00f3n cient\u00edfica del ICES ha propuesto un aumento de sus TAC.<\/p>\n<p>Sin embargo, la organizaci\u00f3n ecologista considera que esta ha sido una oportunidad perdida para bajar los TAC y dar un respiro al resto especies cuya situaci\u00f3n est\u00e1 peor, como es el caso del abadejo, lenguado, la caballa, la cigala o el jurel del oeste. Un a\u00f1o m\u00e1s, el Estado espa\u00f1ol se ha vuelto a posicionar en contra de los recortes propuestos por la ciencia, apostando por la sobrepesca de estas poblaciones.<\/p>\n<p>Seg\u00fan Ecologistas en Acci\u00f3n, en el caso de la merluza del sur, que est\u00e1 mejorando su poblaci\u00f3n, la delegaci\u00f3n espa\u00f1ola podr\u00eda haber apoyado un aumento m\u00e1s conservador para eliminar riesgos de pescar el rango mayor, tal y como recomienda la ciencia, y no poner en riesgo la mejora de la poblaci\u00f3n en los pr\u00f3ximos a\u00f1os.<\/p>\n<p>En el caso de los stocks de aguas profundas, de crecimiento lento y maduraci\u00f3n tard\u00eda \u2013por tanto, muy vulnerables a la pesca\u2013 cabe destacar el caso del besugo, una poblaci\u00f3n en serio declive que, para su recuperaci\u00f3n, se propon\u00eda cerrar la pesquer\u00eda. Sin embargo, se ha propuesto continuar la pesca en 2023 y 2024, a la espera del final de las negociaciones con Reino Unido.<\/p>\n<p>La anguila ha sido una de las protagonistas en las negociaciones. Una especie que est\u00e1 en peligro cr\u00edtico de extinci\u00f3n por la grave p\u00e9rdida de h\u00e1bitat y por la pesca excesiva que ha sufrido durante a\u00f1os. A pesar de ello, se sigue pescando tanto por la flota profesional como por la recreativa de muchos pa\u00edses de Europa. La propuesta de la Comisi\u00f3n ha salido adelante: duplicar la veda existente actualmente, de tres a seis meses, aunque con la posibilidad de que cada Estado miembro decida las \u00e9pocas de cierre; y prohibir la pesca recreativa de la especie, pr\u00e1ctica que no tiene ninguna justificaci\u00f3n social ni de seguridad alimentaria. Ecologistas en Acci\u00f3n ha reconocido que el acuerdo va en buena direcci\u00f3n, aunque queda mucho por hacer y las medidas siguen siendo insuficientes, puesto que la ciencia recomienda acabar completamente con la mortalidad por pesca de la especie para permitir su recuperaci\u00f3n. Tambi\u00e9n debe de haber medidas de cara a la recuperaci\u00f3n del h\u00e1bitat de esta especie.<\/p>\n<p>Otro de los grandes debates ha sido el Mediterr\u00e1neo. Parece que el esfuerzo pesquero \u2013los d\u00edas que se permite salir a pescar\u2013 va a reducirse un 7 % para la flota de arrastre, frente al 7.5 % de reducci\u00f3n que propon\u00eda la Comisi\u00f3n Europea. Esta reducci\u00f3n va asociada a un mecanismo de compensaci\u00f3n del 3,5 % de los d\u00edas a los barcos que apliquen medidas de selectividad y cierres. Por tanto, no suponen un recorte dr\u00e1stico para los barcos que adopten estas medidas.<\/p>\n<p>La organizaci\u00f3n ecologista considera que la reducci\u00f3n del esfuerzo pesquero es necesaria debido al estado desastroso de las poblaciones en el Mediterr\u00e1neo, donde el 85 % de las poblaciones evaluadas est\u00e1n sobreexplotadas. Asimismo, reitera la necesidad de seguir incentivando la selectividad para reducir la captura de juveniles y cierres permanentes de h\u00e1bitats esenciales, como zonas de cr\u00eda y desove, al establecer el reparto de d\u00edas de pesca dentro de nuestra propia flota.<\/p>\n<p><strong>Sobrepesca en plena crisis de p\u00e9rdida de biodiversidad<\/strong><\/p>\n<p>La \u00faltima evaluaci\u00f3n cient\u00edfica publicada por el Comit\u00e9 Cient\u00edfico, T\u00e9cnico y Econ\u00f3mico de Pesca evidencia que, a pesar de que en los \u00faltimos a\u00f1os la situaci\u00f3n de las pesquer\u00edas en el Atl\u00e1ntico noreste ha mejorado, el 28 % de las poblaciones estudiadas est\u00e1n sobreexplotadas, y el 38 % fuera de los l\u00edmites biol\u00f3gicos sostenibles. En el Mediterr\u00e1neo la situaci\u00f3n no mejora, ya que solo el 15 % de las poblaciones se encuentran no sobreexplotados.<\/p>\n<p>Ecologistas en Acci\u00f3n ha recordado que estos d\u00edas los l\u00edderes pol\u00edticos de todo el mundo se encuentran en Canad\u00e1 reunidos en la COP15 de la Convenci\u00f3n de la Diversidad Biol\u00f3gica, con la obligaci\u00f3n de adoptar una hoja de ruta mundial para revertir la p\u00e9rdida de biodiversidad antes de 2030. Por ello, no es de recibo que en la capital belga se sigan adoptando TAC y cuotas por encima de las recomendaciones cient\u00edficas perpetuando as\u00ed la sobrepesca.<\/p>\n<p>Para la organizaci\u00f3n ecologista, ya no hay margen de error: en palabras de la UNESCO, \u201csi no se act\u00faa, m\u00e1s de la mitad de las especies marinas del mundo podr\u00edan estar al borde de la extinci\u00f3n en el a\u00f1o 2100\u201d. Cecilia del Castillo Moro, portavoz de Ecologistas en Acci\u00f3n, ha a\u00f1adido: \u201cLa biodiversidad marina tiene un papel esencial en la salud del planeta. Adem\u00e1s, supone una importante fuente de alimentaci\u00f3n para millones de personas en todo el mundo. La pesca depende del estado saludable de esta biodiversidad y las p\u00e9rdidas socioecon\u00f3micas a largo plazo ser\u00e1n mayores que las ganancias a corto plazo si el Consejo de la UE, con el apoyo del Estado espa\u00f1ol, sigue apostando por pescar m\u00e1s en lugar de pescar mejor.\u201d<\/p>","protected":false},"excerpt":{"rendered":"<p>El 2023 tampoco ver\u00e1 el fin de la sobrepesca Tras dos d\u00edas de negociaciones a puerta cerrada en el Consejo de la UE, se han establecido los l\u00edmites de capturas para las poblaciones de peces del Atl\u00e1ntico nororiental, incluyendo las especies del fondo, y el futuro de las poblaciones del Mediterr\u00e1neo para el 2023. Ecologistas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":71684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2711,2465],"tags":[2478],"class_list":["post-71683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emergencia-climatica","category-informativos","tag-ecologia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El 2023 tampoco ver\u00e1 el fin de la sobrepesca - DLVRADIO<\/title>\n<meta name=\"description\" content=\"El 2023 tampoco ver\u00e1 el fin de la sobrepesca Tras dos d\u00edas de negociaciones a puerta cerrada en el Consejo de la UE, se han establecido los l\u00edmites de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El 2023 tampoco ver\u00e1 el fin de la sobrepesca - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"El 2023 tampoco ver\u00e1 el fin de la sobrepesca Tras dos d\u00edas de negociaciones a puerta cerrada en el Consejo de la UE, se han establecido los l\u00edmites de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-15T10:37:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2022\/12\/El-2023-tampoco-vera-el-fin-de-la-sobrepesca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1511\" \/>\n\t<meta property=\"og:image:height\" content=\"1511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DLV RADIO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\\\/\"},\"author\":{\"name\":\"DLV RADIO\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\"},\"headline\":\"El 2023 tampoco ver\u00e1 el fin de la sobrepesca\",\"datePublished\":\"2022-12-15T10:37:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\\\/\"},\"wordCount\":1173,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/El-2023-tampoco-vera-el-fin-de-la-sobrepesca.jpg\",\"keywords\":[\"ecolog\u00eda\"],\"articleSection\":[\"Emergencia clim\u00e1tica\",\"Informativos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\\\/\",\"name\":\"El 2023 tampoco ver\u00e1 el fin de la sobrepesca - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/El-2023-tampoco-vera-el-fin-de-la-sobrepesca.jpg\",\"datePublished\":\"2022-12-15T10:37:06+00:00\",\"description\":\"El 2023 tampoco ver\u00e1 el fin de la sobrepesca Tras dos d\u00edas de negociaciones a puerta cerrada en el Consejo de la UE, se han establecido los l\u00edmites de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/El-2023-tampoco-vera-el-fin-de-la-sobrepesca.jpg\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/El-2023-tampoco-vera-el-fin-de-la-sobrepesca.jpg\",\"width\":1511,\"height\":1511,\"caption\":\"El 2023 tampoco ver\u00e1 el fin de la sobrepesca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El 2023 tampoco ver\u00e1 el fin de la sobrepesca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\",\"name\":\"DLV RADIO\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El 2023 tampoco ver\u00e1 el fin de la sobrepesca - DLVRADIO","description":"El 2023 tampoco ver\u00e1 el fin de la sobrepesca Tras dos d\u00edas de negociaciones a puerta cerrada en el Consejo de la UE, se han establecido los l\u00edmites de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/","og_locale":"en_US","og_type":"article","og_title":"El 2023 tampoco ver\u00e1 el fin de la sobrepesca - DLVRADIO","og_description":"El 2023 tampoco ver\u00e1 el fin de la sobrepesca Tras dos d\u00edas de negociaciones a puerta cerrada en el Consejo de la UE, se han establecido los l\u00edmites de","og_url":"https:\/\/dlvradio.es\/en\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2022-12-15T10:37:06+00:00","og_image":[{"width":1511,"height":1511,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2022\/12\/El-2023-tampoco-vera-el-fin-de-la-sobrepesca.jpg","type":"image\/jpeg"}],"author":"DLV RADIO","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/"},"author":{"name":"DLV RADIO","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de"},"headline":"El 2023 tampoco ver\u00e1 el fin de la sobrepesca","datePublished":"2022-12-15T10:37:06+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/"},"wordCount":1173,"commentCount":0,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2022\/12\/El-2023-tampoco-vera-el-fin-de-la-sobrepesca.jpg","keywords":["ecolog\u00eda"],"articleSection":["Emergencia clim\u00e1tica","Informativos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/","url":"https:\/\/dlvradio.es\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/","name":"El 2023 tampoco ver\u00e1 el fin de la sobrepesca - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2022\/12\/El-2023-tampoco-vera-el-fin-de-la-sobrepesca.jpg","datePublished":"2022-12-15T10:37:06+00:00","description":"El 2023 tampoco ver\u00e1 el fin de la sobrepesca Tras dos d\u00edas de negociaciones a puerta cerrada en el Consejo de la UE, se han establecido los l\u00edmites de","breadcrumb":{"@id":"https:\/\/dlvradio.es\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2022\/12\/El-2023-tampoco-vera-el-fin-de-la-sobrepesca.jpg","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2022\/12\/El-2023-tampoco-vera-el-fin-de-la-sobrepesca.jpg","width":1511,"height":1511,"caption":"El 2023 tampoco ver\u00e1 el fin de la sobrepesca"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/el-2023-tampoco-vera-el-fin-de-la-sobrepesca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"El 2023 tampoco ver\u00e1 el fin de la sobrepesca"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de","name":"DLV RADIO","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/71683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=71683"}],"version-history":[{"count":0,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/71683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/71684"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=71683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=71683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=71683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}