{"id":71685,"date":"2022-12-18T13:03:22","date_gmt":"2022-12-18T12:03:22","guid":{"rendered":"https:\/\/dlvradio.es\/en-lescola-con-nuria-142\/"},"modified":"2022-12-18T13:03:22","modified_gmt":"2022-12-18T12:03:22","slug":"en-lescola-con-nuria-142","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/en-lescola-con-nuria-142\/","title":{"rendered":"At L&#039;Escola with N\u00faria, 142"},"content":{"rendered":"<iframe src=\"https:\/\/www.ivoox.com\/player_ej_100037933_6_1.html?c1=0ebeb7\" width=\"100%\" height=\"200\" frameborder=\"0\" allowfullscreen=\"\" scrolling=\"no\" loading=\"lazy\"><\/iframe>\n\n\n<h6><img decoding=\"async\" class=\"alignleft wp-image-7754 size-thumbnail\" src=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>Ya estamos aqu\u00ed otra semana m\u00e1s con En L\u2019Escola con N\u00faria. Esta semana nuestra compa\u00f1era entrevista a Agust\u00edn Franco Luque profesor de econom\u00eda en la Universidad de Extremadura, sobre su nuevo libro <strong>\u00abRealismo Patriarcal\u00bb <\/strong>Nos trasladamos a Per\u00fa donde se est\u00e1n viviendo unos momentos convulsos. \u00bfPor qu\u00e9 hablan de golpe de Estado en Espa\u00f1a? \u00bfQu\u00e9 les pasa a los j\u00f3venes no usan cond\u00f3n?, no es solo para no quedarse embarazada, si no una manera de evitar enfermedades de transmisi\u00f3n sexual, como el SIDA\u2026 Cerramos como siempre con El Rata de la semana.<\/h6>","protected":false},"excerpt":{"rendered":"<p>Ya estamos aqu\u00ed otra semana m\u00e1s con En L\u2019Escola con N\u00faria. Esta semana nuestra compa\u00f1era entrevista a Agust\u00edn Franco Luque profesor de econom\u00eda en la Universidad de Extremadura, sobre su nuevo libro \u00abRealismo Patriarcal\u00bb Nos trasladamos a Per\u00fa donde se est\u00e1n viviendo unos momentos convulsos. \u00bfPor qu\u00e9 hablan de golpe de Estado en Espa\u00f1a? \u00bfQu\u00e9 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2560],"tags":[2495,2643,2473],"class_list":["post-71685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-lescola-con-nuria","tag-entrevistas","tag-magazin","tag-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En L&#039;Escola con N\u00faria, 142 - DLVRADIO<\/title>\n<meta name=\"description\" content=\"Ya estamos aqu\u00ed otra semana m\u00e1s con En L\u2019Escola con N\u00faria. Esta semana nuestra compa\u00f1era entrevista a Agust\u00edn Franco Luque profesor de econom\u00eda en la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/en-lescola-con-nuria-142\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En L&#039;Escola con N\u00faria, 142 - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"Ya estamos aqu\u00ed otra semana m\u00e1s con En L\u2019Escola con N\u00faria. Esta semana nuestra compa\u00f1era entrevista a Agust\u00edn Franco Luque profesor de econom\u00eda en la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/en-lescola-con-nuria-142\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-18T12:03:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1511\" \/>\n\t<meta property=\"og:image:height\" content=\"1511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DLV RADIO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-142\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-142\\\/\"},\"author\":{\"name\":\"DLV RADIO\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\"},\"headline\":\"En L&#8217;Escola con N\u00faria, 142\",\"datePublished\":\"2022-12-18T12:03:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-142\\\/\"},\"wordCount\":109,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-142\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/LEscola-nu.jpg\",\"keywords\":[\"Entrevistas\",\"magaz\u00edn\",\"noticias\"],\"articleSection\":[\"En L'Escola con N\u00faria\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-142\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-142\\\/\",\"name\":\"En L'Escola con N\u00faria, 142 - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-142\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-142\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/LEscola-nu.jpg\",\"datePublished\":\"2022-12-18T12:03:22+00:00\",\"description\":\"Ya estamos aqu\u00ed otra semana m\u00e1s con En L\u2019Escola con N\u00faria. Esta semana nuestra compa\u00f1era entrevista a Agust\u00edn Franco Luque profesor de econom\u00eda en la\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-142\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-142\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-142\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/LEscola-nu.jpg\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/LEscola-nu.jpg\",\"width\":1511,\"height\":1511,\"caption\":\"L'Escola nu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-142\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En L&#8217;Escola con N\u00faria, 142\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\",\"name\":\"DLV RADIO\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En L'Escola con N\u00faria, 142 - DLVRADIO","description":"Ya estamos aqu\u00ed otra semana m\u00e1s con En L\u2019Escola con N\u00faria. Esta semana nuestra compa\u00f1era entrevista a Agust\u00edn Franco Luque profesor de econom\u00eda en la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/en-lescola-con-nuria-142\/","og_locale":"en_US","og_type":"article","og_title":"En L'Escola con N\u00faria, 142 - DLVRADIO","og_description":"Ya estamos aqu\u00ed otra semana m\u00e1s con En L\u2019Escola con N\u00faria. Esta semana nuestra compa\u00f1era entrevista a Agust\u00edn Franco Luque profesor de econom\u00eda en la","og_url":"https:\/\/dlvradio.es\/en\/en-lescola-con-nuria-142\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2022-12-18T12:03:22+00:00","og_image":[{"width":1511,"height":1511,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg","type":"image\/jpeg"}],"author":"DLV RADIO","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-142\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-142\/"},"author":{"name":"DLV RADIO","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de"},"headline":"En L&#8217;Escola con N\u00faria, 142","datePublished":"2022-12-18T12:03:22+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-142\/"},"wordCount":109,"commentCount":0,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-142\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg","keywords":["Entrevistas","magaz\u00edn","noticias"],"articleSection":["En L'Escola con N\u00faria"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-142\/","url":"https:\/\/dlvradio.es\/en-lescola-con-nuria-142\/","name":"En L'Escola con N\u00faria, 142 - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-142\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-142\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg","datePublished":"2022-12-18T12:03:22+00:00","description":"Ya estamos aqu\u00ed otra semana m\u00e1s con En L\u2019Escola con N\u00faria. Esta semana nuestra compa\u00f1era entrevista a Agust\u00edn Franco Luque profesor de econom\u00eda en la","breadcrumb":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-142\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/en-lescola-con-nuria-142\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-142\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg","width":1511,"height":1511,"caption":"L'Escola nu"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-142\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"En L&#8217;Escola con N\u00faria, 142"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de","name":"DLV RADIO","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/71685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=71685"}],"version-history":[{"count":0,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/71685\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/70815"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=71685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=71685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=71685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}