{"id":71795,"date":"2023-02-19T12:24:56","date_gmt":"2023-02-19T11:24:56","guid":{"rendered":"https:\/\/dlvradio.es\/en-lescola-con-nuria-150\/"},"modified":"2023-02-19T12:24:56","modified_gmt":"2023-02-19T11:24:56","slug":"en-lescola-con-nuria-150","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/en-lescola-con-nuria-150\/","title":{"rendered":"En L&#8217;Escola con N\u00faria, 150"},"content":{"rendered":"<iframe src=\"https:\/\/www.ivoox.com\/player_ej_103319891_6_1.html?c1=0ebeb7\" width=\"100%\" height=\"200\" frameborder=\"0\" allowfullscreen=\"\" scrolling=\"no\" loading=\"lazy\"><\/iframe>\n\n\n<h6><img decoding=\"async\" class=\"alignleft wp-image-7754 size-thumbnail\" src=\"https:\/\/dlvradio.es\/copia\/wp-content\/uploads\/2021\/10\/LEscola-nu-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>Ya estamos con el magaz\u00edn de L\u2019Escola, esta semana es especial porque hacemos ya nuestro 150 programa en DLVRADIO. Esta semana hablamos con N\u00faria Murl\u00e0 i Ribot experta en derechos de los animales sobre la nueva Ley de bienestar animal. En ella hemos detectado algunas cosas muy raras. El tren del Ohio (EE. UU) Chemical Disaster, lo que no nos han contado de esta cat\u00e1strofe ecol\u00f3gica. La Infancia que pasa fr\u00edo consecuencia de la pobreza energ\u00e9tica y mientras tanto las grandes empresas de energ\u00eda de este pa\u00eds llen\u00e1ndose los bolsillos. Hoy os vamos a hablar del Carnaval m\u00e1s raro del mundo. Cerramos con #ElRata de la semana.<\/h6>","protected":false},"excerpt":{"rendered":"<p>Ya estamos con el magaz\u00edn de L\u2019Escola, esta semana es especial porque hacemos ya nuestro 150 programa en DLVRADIO. Esta semana hablamos con N\u00faria Murl\u00e0 i Ribot experta en derechos de los animales sobre la nueva Ley de bienestar animal. En ella hemos detectado algunas cosas muy raras. El tren del Ohio (EE. UU) Chemical [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2560],"tags":[2495,2566,2643],"class_list":["post-71795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-lescola-con-nuria","tag-entrevistas","tag-leyes","tag-magazin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En L&#039;Escola con N\u00faria, 150 - DLVRADIO<\/title>\n<meta name=\"description\" content=\"Ya estamos con el magaz\u00edn de L\u2019Escola, esta semana es especial porque hacemos ya nuestro 150 programa en DLVRADIO. Esta semana hablamos con N\u00faria Murl\u00e0 i\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/en-lescola-con-nuria-150\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En L&#039;Escola con N\u00faria, 150 - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"Ya estamos con el magaz\u00edn de L\u2019Escola, esta semana es especial porque hacemos ya nuestro 150 programa en DLVRADIO. Esta semana hablamos con N\u00faria Murl\u00e0 i\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/en-lescola-con-nuria-150\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-19T11:24:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1511\" \/>\n\t<meta property=\"og:image:height\" content=\"1511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DLV RADIO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-150\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-150\\\/\"},\"author\":{\"name\":\"DLV RADIO\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\"},\"headline\":\"En L&#8217;Escola con N\u00faria, 150\",\"datePublished\":\"2023-02-19T11:24:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-150\\\/\"},\"wordCount\":123,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-150\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/LEscola-nu.jpg\",\"keywords\":[\"Entrevistas\",\"leyes\",\"magaz\u00edn\"],\"articleSection\":[\"En L'Escola con N\u00faria\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-150\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-150\\\/\",\"name\":\"En L'Escola con N\u00faria, 150 - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-150\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-150\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/LEscola-nu.jpg\",\"datePublished\":\"2023-02-19T11:24:56+00:00\",\"description\":\"Ya estamos con el magaz\u00edn de L\u2019Escola, esta semana es especial porque hacemos ya nuestro 150 programa en DLVRADIO. Esta semana hablamos con N\u00faria Murl\u00e0 i\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-150\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-150\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-150\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/LEscola-nu.jpg\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/LEscola-nu.jpg\",\"width\":1511,\"height\":1511,\"caption\":\"L'Escola nu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/en-lescola-con-nuria-150\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En L&#8217;Escola con N\u00faria, 150\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/7d533f9f89b13e3a3f2ba7f67d6412de\",\"name\":\"DLV RADIO\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En L'Escola con N\u00faria, 150 - DLVRADIO","description":"Ya estamos con el magaz\u00edn de L\u2019Escola, esta semana es especial porque hacemos ya nuestro 150 programa en DLVRADIO. Esta semana hablamos con N\u00faria Murl\u00e0 i","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/en-lescola-con-nuria-150\/","og_locale":"en_US","og_type":"article","og_title":"En L'Escola con N\u00faria, 150 - DLVRADIO","og_description":"Ya estamos con el magaz\u00edn de L\u2019Escola, esta semana es especial porque hacemos ya nuestro 150 programa en DLVRADIO. Esta semana hablamos con N\u00faria Murl\u00e0 i","og_url":"https:\/\/dlvradio.es\/en\/en-lescola-con-nuria-150\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2023-02-19T11:24:56+00:00","og_image":[{"width":1511,"height":1511,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg","type":"image\/jpeg"}],"author":"DLV RADIO","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-150\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-150\/"},"author":{"name":"DLV RADIO","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de"},"headline":"En L&#8217;Escola con N\u00faria, 150","datePublished":"2023-02-19T11:24:56+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-150\/"},"wordCount":123,"commentCount":0,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-150\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg","keywords":["Entrevistas","leyes","magaz\u00edn"],"articleSection":["En L'Escola con N\u00faria"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-150\/","url":"https:\/\/dlvradio.es\/en-lescola-con-nuria-150\/","name":"En L'Escola con N\u00faria, 150 - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-150\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-150\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg","datePublished":"2023-02-19T11:24:56+00:00","description":"Ya estamos con el magaz\u00edn de L\u2019Escola, esta semana es especial porque hacemos ya nuestro 150 programa en DLVRADIO. Esta semana hablamos con N\u00faria Murl\u00e0 i","breadcrumb":{"@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-150\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/en-lescola-con-nuria-150\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-150\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2021\/10\/LEscola-nu.jpg","width":1511,"height":1511,"caption":"L'Escola nu"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/en-lescola-con-nuria-150\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"En L&#8217;Escola con N\u00faria, 150"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/7d533f9f89b13e3a3f2ba7f67d6412de","name":"DLV RADIO","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/71795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=71795"}],"version-history":[{"count":0,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/71795\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/70815"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=71795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=71795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=71795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}