{"id":75222,"date":"2024-12-03T12:24:37","date_gmt":"2024-12-03T11:24:37","guid":{"rendered":"https:\/\/dlvradio.es\/?p=75222"},"modified":"2024-12-03T13:29:34","modified_gmt":"2024-12-03T12:29:34","slug":"presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/","title":{"rendered":"Presentaci\u00f3n del libro \u00abPaqui la Taqui\u00bb de Nuria Gonz\u00e1lez"},"content":{"rendered":"<p>El pr\u00f3ximo 9\/12\/2024 en Pamplona, en la sala Geltoki (situada en la antigua estaci\u00f3n de autobuses) a las <span style=\"color: #ff0000;\">18:15<\/span>h. Tendr\u00e1 lugar la presentaci\u00f3n del libro de Nuria Gonz\u00e1lez L\u00f3pez <strong>\u00abPaqui la Taqui\u00bb<\/strong>. (Tiene usted en sus manos una peligrosa arma de destrucci\u00f3n masiva del aletargamiento, el conformismo y el aburrimiento).<\/p>\n<p>Se podr\u00e1 adquirir el libro en la misma sala, gracias a la Librer\u00eda Eguzki Sarriguren que tendr\u00e1 un stand. Al finalizar la presentaci\u00f3n la autora firmar\u00e1 libros.<\/p>\n<p>Sinopsis del libro:<\/p>\n<p>Tiene usted en sus manos una peligrosa arma de destrucci\u00f3n masiva del aletargamiento, el conformismo y el aburrimiento. <strong>Paqui La Taqui<\/strong>. Aventuras de una reportera feminista en la era posmolerda, creada por el inigualable dibujante <strong>Pepe Farruco<\/strong> y la abogada <strong>N\u00faria Gonz\u00e1lez L\u00f3pez<\/strong> en su versi\u00f3n m\u00e1s canalla, la de <strong>The Perry<\/strong>, les ofrece un viaje por todos los temas de la actualidad m\u00e1s candente en el que no deja t\u00edtere con cabeza. Espa\u00f1a, el mundo y hasta el universo sideral y tambi\u00e9n todos los malos y algunas buenas, est\u00e1n en este libro de textos e ilustraciones, que reivindica el pensamiento cr\u00edtico sobre lo que pasa a nuestro alrededor y el sentido del humor, cada vez m\u00e1s escaso y cada vez m\u00e1s necesario. Pase y conozca a esta especie de nueva Trinidad Atea, gracias a las diosas del feminismo, compuesta por La Paqui, La Perry y Farruco y p\u00e1selo genial haciendo ejercicio mental, que adem\u00e1s puede ser compatible con hacerlo tomando cualquier bebida fresquita. \u00a1\u00a1Salud!!<\/p>","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo 9\/12\/2024 en Pamplona, en la sala Geltoki (situada en la antigua estaci\u00f3n de autobuses) a las 18:15h. Tendr\u00e1 lugar la presentaci\u00f3n del libro de Nuria Gonz\u00e1lez L\u00f3pez \u00abPaqui la Taqui\u00bb. (Tiene usted en sus manos una peligrosa arma de destrucci\u00f3n masiva del aletargamiento, el conformismo y el aburrimiento). Se podr\u00e1 adquirir el libro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":75310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2767],"tags":[2486,2471,2644],"class_list":["post-75222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-ocio-y-musica","tag-cultura","tag-feminismo","tag-ocio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentaci\u00f3n del libro &quot;Paqui la Taqui&quot; de Nuria Gonz\u00e1lez - DLVRADIO<\/title>\n<meta name=\"description\" content=\"El pr\u00f3ximo 9\/12\/2024 en Pamplona, en la sala Geltoki (situada en la antigua estaci\u00f3n de autobuses) a las 18:15h. Tendr\u00e1 lugar la presentaci\u00f3n del libro de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentaci\u00f3n del libro &quot;Paqui la Taqui&quot; de Nuria Gonz\u00e1lez - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo 9\/12\/2024 en Pamplona, en la sala Geltoki (situada en la antigua estaci\u00f3n de autobuses) a las 18:15h. Tendr\u00e1 lugar la presentaci\u00f3n del libro de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-03T11:24:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-03T12:29:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2024\/11\/www.dlvradio.es-1080-x-1080-px-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"doominio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\\\/\"},\"author\":{\"name\":\"doominio\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\"},\"headline\":\"Presentaci\u00f3n del libro \u00abPaqui la Taqui\u00bb de Nuria Gonz\u00e1lez\",\"datePublished\":\"2024-12-03T11:24:37+00:00\",\"dateModified\":\"2024-12-03T12:29:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\\\/\"},\"wordCount\":279,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/www.dlvradio.es-1080-x-1080-px-1.png\",\"keywords\":[\"cultura\",\"feminismo\",\"ocio\"],\"articleSection\":[\"Cultura, ocio y m\u00fasica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\\\/\",\"name\":\"Presentaci\u00f3n del libro \\\"Paqui la Taqui\\\" de Nuria Gonz\u00e1lez - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/www.dlvradio.es-1080-x-1080-px-1.png\",\"datePublished\":\"2024-12-03T11:24:37+00:00\",\"dateModified\":\"2024-12-03T12:29:34+00:00\",\"description\":\"El pr\u00f3ximo 9\\\/12\\\/2024 en Pamplona, en la sala Geltoki (situada en la antigua estaci\u00f3n de autobuses) a las 18:15h. Tendr\u00e1 lugar la presentaci\u00f3n del libro de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/www.dlvradio.es-1080-x-1080-px-1.png\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/www.dlvradio.es-1080-x-1080-px-1.png\",\"width\":1080,\"height\":1080,\"caption\":\"Presentaci\u00f3n del libro \\\"Paqui la Taqui\\\" de Nuria Gonz\u00e1lez\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentaci\u00f3n del libro &#8220;Paqui la Taqui&#8221; de Nuria Gonz\u00e1lez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\",\"name\":\"doominio\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentaci\u00f3n del libro \"Paqui la Taqui\" de Nuria Gonz\u00e1lez - DLVRADIO","description":"El pr\u00f3ximo 9\/12\/2024 en Pamplona, en la sala Geltoki (situada en la antigua estaci\u00f3n de autobuses) a las 18:15h. Tendr\u00e1 lugar la presentaci\u00f3n del libro de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/","og_locale":"en_US","og_type":"article","og_title":"Presentaci\u00f3n del libro \"Paqui la Taqui\" de Nuria Gonz\u00e1lez - DLVRADIO","og_description":"El pr\u00f3ximo 9\/12\/2024 en Pamplona, en la sala Geltoki (situada en la antigua estaci\u00f3n de autobuses) a las 18:15h. Tendr\u00e1 lugar la presentaci\u00f3n del libro de","og_url":"https:\/\/dlvradio.es\/en\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2024-12-03T11:24:37+00:00","article_modified_time":"2024-12-03T12:29:34+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2024\/11\/www.dlvradio.es-1080-x-1080-px-1.png","type":"image\/png"}],"author":"doominio","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/"},"author":{"name":"doominio","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa"},"headline":"Presentaci\u00f3n del libro \u00abPaqui la Taqui\u00bb de Nuria Gonz\u00e1lez","datePublished":"2024-12-03T11:24:37+00:00","dateModified":"2024-12-03T12:29:34+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/"},"wordCount":279,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2024\/11\/www.dlvradio.es-1080-x-1080-px-1.png","keywords":["cultura","feminismo","ocio"],"articleSection":["Cultura, ocio y m\u00fasica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/","url":"https:\/\/dlvradio.es\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/","name":"Presentaci\u00f3n del libro \"Paqui la Taqui\" de Nuria Gonz\u00e1lez - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2024\/11\/www.dlvradio.es-1080-x-1080-px-1.png","datePublished":"2024-12-03T11:24:37+00:00","dateModified":"2024-12-03T12:29:34+00:00","description":"El pr\u00f3ximo 9\/12\/2024 en Pamplona, en la sala Geltoki (situada en la antigua estaci\u00f3n de autobuses) a las 18:15h. Tendr\u00e1 lugar la presentaci\u00f3n del libro de","breadcrumb":{"@id":"https:\/\/dlvradio.es\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2024\/11\/www.dlvradio.es-1080-x-1080-px-1.png","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2024\/11\/www.dlvradio.es-1080-x-1080-px-1.png","width":1080,"height":1080,"caption":"Presentaci\u00f3n del libro \"Paqui la Taqui\" de Nuria Gonz\u00e1lez"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/presentacion-del-libro-paqui-la-taqui-de-nuria-gonzalez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"Presentaci\u00f3n del libro &#8220;Paqui la Taqui&#8221; de Nuria Gonz\u00e1lez"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa","name":"doominio","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/75222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=75222"}],"version-history":[{"count":2,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/75222\/revisions"}],"predecessor-version":[{"id":75255,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/75222\/revisions\/75255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/75310"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=75222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=75222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=75222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}