{"id":77303,"date":"2025-05-24T19:08:00","date_gmt":"2025-05-24T17:08:00","guid":{"rendered":"https:\/\/dlvradio.es\/?p=77303"},"modified":"2025-05-24T19:08:00","modified_gmt":"2025-05-24T17:08:00","slug":"un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/","title":{"rendered":"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad"},"content":{"rendered":"<h3><strong>Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad<\/strong><\/h3>\n<ul>\n<li><em>Ante la implementaci\u00f3n de la Directiva de Energ\u00edas Renovables (DER III) de la UE, que plantea objetivos para reducir las emisiones de gases de efecto invernadero del sector de transporte y proteger el medio ambiente, Ecologistas en Acci\u00f3n publica un informe que muestra la trampa de pretender descarbonizar el sector de transporte con biocombustibles.<\/em><\/li>\n<li><em>La organizaci\u00f3n ecologista apunta que la promoci\u00f3n de este tipo de carburantes supone una falsa soluci\u00f3n y que es necesario reducir la demanda energ\u00e9tica del transporte y poner l\u00edmites a su crecimiento.<\/em><\/li>\n<\/ul>\n<p>Los Estados miembros de la UE ten\u00edan hasta el 21 de mayo como plazo para implementar la tercera versi\u00f3n de la Directiva de Energ\u00edas Renovables, la DER III, aprobada en 2023. Esta directiva tiene como objetivo aumentar la cuota de energ\u00edas renovables al 45 % para 2030, de cara a reducir las emisiones de gases de efecto invernadero en los sectores de la electricidad, calefacci\u00f3n, refrigeraci\u00f3n y transporte dentro de la UE. Se trata de una medida para combatir el cambio clim\u00e1tico, proteger el medio ambiente y reducir la dependencia energ\u00e9tica.<\/p>\n<p>En lo que respecta a la descarbonizaci\u00f3n del transporte, la Directiva impone un objetivo del 29 % de energ\u00eda renovable para el 2030 o una reducci\u00f3n como m\u00ednimo del 14,5 % de la intensidad de emisiones de gases de efecto invernadero.<\/p>\n<p>Sin embargo, en la actualidad los sectores del transporte proyectan un crecimiento para 2050 que conlleva un aumento en la demanda energ\u00e9tica y de combustible incompatibles con los objetivos de reducci\u00f3n de emisiones e impactos ambientales que plantea la Directiva. Dichos sectores basan su descarbonizaci\u00f3n en la producci\u00f3n de biocombustibles y combustibles supuestamente renovables que, a partir de materias primas limitadas y de dudosa sostenibilidad, generan una presi\u00f3n insostenible sobre los recursos disponibles.<\/p>\n<p>En este marco, Ecologistas en Acci\u00f3n ha publicado el informe \u201cLa falsa soluci\u00f3n de los biocombustibles: aviaci\u00f3n, transporte terrestre y mar\u00edtimo compiten por materias primas limitadas y de dudosa sostenibilidad para descarbonizar el sector del transporte\u201d. El informe muestra la incompatibilidad de perseguir unos objetivos necesarios para la reducci\u00f3n de emisiones y de impactos ambientales del sector de transporte, con una pol\u00edtica basada \u00fanicamente en la promoci\u00f3n de combustibles alternativos.<\/p>\n<p><strong>M\u00e1s de una d\u00e9cada de pol\u00edticas que han contribuido a la deforestaci\u00f3n global<\/strong><\/p>\n<p>Los biocombustibles han sido promovidos en la UE como una soluci\u00f3n clave para reducir las emisiones del sector del transporte, especialmente para los modos de dif\u00edcil electrificaci\u00f3n como el a\u00e9reo y mar\u00edtimo. Sin embargo, varios estudios han demostrado que los biocombustibles procedentes de cultivos pueden generar m\u00e1s emisiones de las que pretenden reducir, teniendo en cuenta aquellas derivadas de los cambios de uso de la tierra y la ampliaci\u00f3n de la frontera agr\u00edcola, contribuyendo a la p\u00e9rdida de biodiversidad.<\/p>\n<p>En 2010 la DER comenz\u00f3 la promoci\u00f3n de los biocombustibles de cultivos como la palma y la soja. Se calcula que en una d\u00e9cada estas pol\u00edticas han contribuido notablemente a la deforestaci\u00f3n global, arrasando potencialmente un \u00e1rea total de bosques del tama\u00f1o de los Pa\u00edses Bajos.<\/p>\n<p>En 2018 la UE acord\u00f3 eliminar gradualmente el aceite de palma para producir biocombustibles para 2030 y comenz\u00f3 a promover alternativas basadas en residuos, como el aceite de cocina usado (UCO), las grasas animales y productos derivados de la palma y otros residuos. Son los denominados biocombustibles avanzados (aquellos que provienen de residuos org\u00e1nicos y no de cultivos). Sin embargo, la sostenibilidad de estos tambi\u00e9n ha sido cuestionada.<\/p>\n<p>En 2023 los pa\u00edses europeos consumieron cerca de siete millones de toneladas de aceite de cocina usado (UCO) para biocombustibles, la gran mayor\u00eda fue utilizado en mezclas de biodi\u00e9sel con di\u00e9sel convencional destinado a coches y camiones. Esta cifra es casi ocho veces superior a las estimaciones de vol\u00famenes recolectados ese mismo a\u00f1o y cuatro veces mayor que el potencial m\u00e1ximo de recogida del continente, con una demanda que crece mucho m\u00e1s r\u00e1pido que la oferta local.<\/p>\n<p>Para llenar el vac\u00edo de suministro, la UE importa cada vez m\u00e1s UCO de China, as\u00ed como de Indonesia y Malasia. Pero a medida que las compa\u00f1\u00edas a\u00e9reas empiezan a demandar biocombustibles de aceite de cocina usado para la aviaci\u00f3n, la demanda est\u00e1 superando lo que se puede recoger de forma sostenible.<\/p>\n<p>En el caso de los residuos derivados de la palma, uno de los biocombustibles considerados avanzados m\u00e1s utilizados es el POME (efluentes de molino de aceite de palma, por sus siglas en ingl\u00e9s). Los datos analizados en un reciente informe de T&amp;E indican que se est\u00e1n declarando m\u00e1s residuos de aceite de palma de los que realmente es posible generar, lo que sugiere una alta probabilidad de fraude y que se est\u00e9 produciendo biocombustibles con aceite virgen de palma etiquetado como aceite de cocina usado.<\/p>\n<p>Por todo ello, Ecologistas en Acci\u00f3n advierte que es fundamental adoptar estrategias m\u00e1s sostenibles. En primer lugar, se\u00f1ala la necesidad de reducir la demanda energ\u00e9tica del transporte, para lo cual es necesario poner l\u00edmites a su crecimiento. Adem\u00e1s, la organizaci\u00f3n a\u00f1ade otras medidas necesarias:\u00a0 reforzar las pol\u00edticas europeas y de los Estados miembros para que eliminen los biocombustibles de cultivos, especialmente los de palma y soja; restringir las importaciones, centr\u00e1ndose \u00fanicamente en la disponibilidad dom\u00e9stica de los residuos; y mejorar la regulaci\u00f3n y la trazabilidad para evitar fraudes.<\/p>\n<p>Marta Orihuel, portavoz de Ecologistas en Acci\u00f3n, ha declarado: \u201cLa creciente competencia por los mismos recursos entre la aviaci\u00f3n, el transporte terrestre y el mar\u00edtimo amenaza con generar impactos ambientales negativos como la deforestaci\u00f3n, las emisiones indirectas y la crisis en la seguridad alimentaria. La transici\u00f3n hacia los biocombustibles est\u00e1 lejos de ser una soluci\u00f3n clim\u00e1tica real\u201d.<\/p>\n<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/05\/La-falsa-solucion-de-los-biocombustibles.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">La-falsa-solucion-de-los-biocombustibles<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad Ante la implementaci\u00f3n de la Directiva de Energ\u00edas Renovables (DER III) de la UE, que plantea objetivos para reducir las emisiones de gases de efecto invernadero del sector de transporte y proteger el medio ambiente, Ecologistas en Acci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":77305,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2711],"tags":[2478,2608],"class_list":["post-77303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emergencia-climatica","tag-ecologia","tag-union-europea"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad - DLVRADIO<\/title>\n<meta name=\"description\" content=\"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad Ante la implementaci\u00f3n de la Directiva de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad Ante la implementaci\u00f3n de la Directiva de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-24T17:08:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/05\/Imagen1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"567\" \/>\n\t<meta property=\"og:image:height\" content=\"551\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"doominio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\\\/\"},\"author\":{\"name\":\"doominio\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\"},\"headline\":\"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad\",\"datePublished\":\"2025-05-24T17:08:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\\\/\"},\"wordCount\":1050,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Imagen1.png\",\"keywords\":[\"ecolog\u00eda\",\"uni\u00f3n europea\"],\"articleSection\":[\"Emergencia clim\u00e1tica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\\\/\",\"name\":\"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Imagen1.png\",\"datePublished\":\"2025-05-24T17:08:00+00:00\",\"description\":\"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad Ante la implementaci\u00f3n de la Directiva de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Imagen1.png\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Imagen1.png\",\"width\":567,\"height\":551,\"caption\":\"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\",\"name\":\"doominio\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad - DLVRADIO","description":"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad Ante la implementaci\u00f3n de la Directiva de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/","og_locale":"en_US","og_type":"article","og_title":"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad - DLVRADIO","og_description":"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad Ante la implementaci\u00f3n de la Directiva de","og_url":"https:\/\/dlvradio.es\/en\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2025-05-24T17:08:00+00:00","og_image":[{"width":567,"height":551,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/05\/Imagen1.png","type":"image\/png"}],"author":"doominio","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/"},"author":{"name":"doominio","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa"},"headline":"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad","datePublished":"2025-05-24T17:08:00+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/"},"wordCount":1050,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/05\/Imagen1.png","keywords":["ecolog\u00eda","uni\u00f3n europea"],"articleSection":["Emergencia clim\u00e1tica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/","url":"https:\/\/dlvradio.es\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/","name":"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/05\/Imagen1.png","datePublished":"2025-05-24T17:08:00+00:00","description":"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad Ante la implementaci\u00f3n de la Directiva de","breadcrumb":{"@id":"https:\/\/dlvradio.es\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/05\/Imagen1.png","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/05\/Imagen1.png","width":567,"height":551,"caption":"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/un-nuevo-informe-senala-que-el-impulso-de-los-biocombustibles-agravara-la-crisis-climatica-y-de-biodiversidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"Un nuevo informe se\u00f1ala que el impulso de los biocombustibles agravar\u00e1 la crisis clim\u00e1tica y de biodiversidad"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa","name":"doominio","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/77303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=77303"}],"version-history":[{"count":1,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/77303\/revisions"}],"predecessor-version":[{"id":77306,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/77303\/revisions\/77306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/77305"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=77303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=77303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=77303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}