{"id":77567,"date":"2025-07-06T10:50:32","date_gmt":"2025-07-06T08:50:32","guid":{"rendered":"https:\/\/dlvradio.es\/?p=77567"},"modified":"2025-07-06T11:03:29","modified_gmt":"2025-07-06T09:03:29","slug":"mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/","title":{"rendered":"MUJERES HIST\u00d3RICAS, esta semana \u00abAntonia Matos, figura esencial en el panorama del arte guatemalteco\u00bb"},"content":{"rendered":"<p><iframe src=\"https:\/\/www.ivoox.com\/player_ej_151855920_6_1.html?c1=0ebeb7\" width=\"100%\" height=\"200\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p dir=\"auto\" data-pm-slice=\"1 1 []\">Antonia Matos emerge como una figura esencial en el vasto y vibrante panorama del arte guatemalteco. Su legado art\u00edstico resuena con una fuerza particular, marcando un hito en la historia cultural de su naci\u00f3n. Es reconocida por una obra pict\u00f3rica prol\u00edfica, caracterizada por su profundidad y su inconfundible sello personal.<\/p>\n<p dir=\"auto\" data-pm-slice=\"1 1 []\">Cada lienzo de Matos refleja una conexi\u00f3n profunda e inquebrantable con su tierra natal, Guatemala. Sus creaciones son un testimonio visual de sus ra\u00edces, de la riqueza cultural y de la esencia de su origen. Al mismo tiempo, su arte se adentra en la exploraci\u00f3n constante de la identidad femenina.<\/p>\n<p dir=\"auto\" data-pm-slice=\"1 1 []\">A trav\u00e9s de sus pinceles, Matos desentra\u00f1a las complejidades de la mujer, sus roles y sus emociones. Su vida estuvo marcada por una dualidad geogr\u00e1fica y cultural, oscilando entre la calidez de Guatemala y el efervescente ambiente de Par\u00eds. Esta dualidad no fue una mera circunstancia, sino una fuerza motriz&#8230;<\/p>\n<p><iframe title=\"MUJERES HIST\u00d3RICAS, esta semana Antonia Matos, figura esencial en el panorama del arte guatemalteco\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/6U4WG9ouqIU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Antonia Matos emerge como una figura esencial en el vasto y vibrante panorama del arte guatemalteco. Su legado art\u00edstico resuena con una fuerza particular, marcando un hito en la historia cultural de su naci\u00f3n. Es reconocida por una obra pict\u00f3rica prol\u00edfica, caracterizada por su profundidad y su inconfundible sello personal. Cada lienzo de Matos refleja [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":77568,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2767,2470],"tags":[2486,2471,2502],"class_list":["post-77567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-ocio-y-musica","category-feminismo","tag-cultura","tag-feminismo","tag-mujer"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MUJERES HIST\u00d3RICAS, esta semana &quot;Antonia Matos, figura esencial en el panorama del arte guatemalteco&quot; - DLVRADIO<\/title>\n<meta name=\"description\" content=\"Antonia Matos emerge como una figura esencial en el vasto y vibrante panorama del arte guatemalteco. Su legado art\u00edstico resuena con una fuerza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MUJERES HIST\u00d3RICAS, esta semana &quot;Antonia Matos, figura esencial en el panorama del arte guatemalteco&quot; - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"Antonia Matos emerge como una figura esencial en el vasto y vibrante panorama del arte guatemalteco. Su legado art\u00edstico resuena con una fuerza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-06T08:50:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-06T09:03:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/07\/Mujeres-historicas-1080-x-1080-px-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"doominio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\\\/\"},\"author\":{\"name\":\"doominio\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\"},\"headline\":\"MUJERES HIST\u00d3RICAS, esta semana \u00abAntonia Matos, figura esencial en el panorama del arte guatemalteco\u00bb\",\"datePublished\":\"2025-07-06T08:50:32+00:00\",\"dateModified\":\"2025-07-06T09:03:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\\\/\"},\"wordCount\":182,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Mujeres-historicas-1080-x-1080-px-1.png\",\"keywords\":[\"cultura\",\"feminismo\",\"Mujer\"],\"articleSection\":[\"Cultura, ocio y m\u00fasica\",\"Feminismo\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\\\/\",\"name\":\"MUJERES HIST\u00d3RICAS, esta semana \\\"Antonia Matos, figura esencial en el panorama del arte guatemalteco\\\" - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Mujeres-historicas-1080-x-1080-px-1.png\",\"datePublished\":\"2025-07-06T08:50:32+00:00\",\"dateModified\":\"2025-07-06T09:03:29+00:00\",\"description\":\"Antonia Matos emerge como una figura esencial en el vasto y vibrante panorama del arte guatemalteco. Su legado art\u00edstico resuena con una fuerza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Mujeres-historicas-1080-x-1080-px-1.png\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Mujeres-historicas-1080-x-1080-px-1.png\",\"width\":1080,\"height\":1080,\"caption\":\"MUJERES HIST\u00d3RICAS, esta semana \\\"Antonia Matos, figura esencial en el panorama del arte guatemalteco\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MUJERES HIST\u00d3RICAS, esta semana \u00abAntonia Matos, figura esencial en el panorama del arte guatemalteco\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\",\"name\":\"doominio\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MUJERES HIST\u00d3RICAS, esta semana \"Antonia Matos, figura esencial en el panorama del arte guatemalteco\" - DLVRADIO","description":"Antonia Matos emerge como una figura esencial en el vasto y vibrante panorama del arte guatemalteco. Su legado art\u00edstico resuena con una fuerza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/","og_locale":"en_US","og_type":"article","og_title":"MUJERES HIST\u00d3RICAS, esta semana \"Antonia Matos, figura esencial en el panorama del arte guatemalteco\" - DLVRADIO","og_description":"Antonia Matos emerge como una figura esencial en el vasto y vibrante panorama del arte guatemalteco. Su legado art\u00edstico resuena con una fuerza","og_url":"https:\/\/dlvradio.es\/en\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2025-07-06T08:50:32+00:00","article_modified_time":"2025-07-06T09:03:29+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/07\/Mujeres-historicas-1080-x-1080-px-1.png","type":"image\/png"}],"author":"doominio","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/"},"author":{"name":"doominio","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa"},"headline":"MUJERES HIST\u00d3RICAS, esta semana \u00abAntonia Matos, figura esencial en el panorama del arte guatemalteco\u00bb","datePublished":"2025-07-06T08:50:32+00:00","dateModified":"2025-07-06T09:03:29+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/"},"wordCount":182,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/07\/Mujeres-historicas-1080-x-1080-px-1.png","keywords":["cultura","feminismo","Mujer"],"articleSection":["Cultura, ocio y m\u00fasica","Feminismo"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/","url":"https:\/\/dlvradio.es\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/","name":"MUJERES HIST\u00d3RICAS, esta semana \"Antonia Matos, figura esencial en el panorama del arte guatemalteco\" - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/07\/Mujeres-historicas-1080-x-1080-px-1.png","datePublished":"2025-07-06T08:50:32+00:00","dateModified":"2025-07-06T09:03:29+00:00","description":"Antonia Matos emerge como una figura esencial en el vasto y vibrante panorama del arte guatemalteco. Su legado art\u00edstico resuena con una fuerza","breadcrumb":{"@id":"https:\/\/dlvradio.es\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/07\/Mujeres-historicas-1080-x-1080-px-1.png","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/07\/Mujeres-historicas-1080-x-1080-px-1.png","width":1080,"height":1080,"caption":"MUJERES HIST\u00d3RICAS, esta semana \"Antonia Matos, figura esencial en el panorama del arte guatemalteco"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/mujeres-historicas-esta-semana-antonia-matos-figura-esencial-en-el-panorama-del-arte-guatemalteco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"MUJERES HIST\u00d3RICAS, esta semana \u00abAntonia Matos, figura esencial en el panorama del arte guatemalteco\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa","name":"doominio","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/77567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=77567"}],"version-history":[{"count":3,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/77567\/revisions"}],"predecessor-version":[{"id":77571,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/77567\/revisions\/77571"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/77568"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=77567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=77567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=77567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}