{"id":78603,"date":"2026-02-01T13:59:30","date_gmt":"2026-02-01T12:59:30","guid":{"rendered":"https:\/\/dlvradio.es\/?p=78603"},"modified":"2026-02-01T13:59:30","modified_gmt":"2026-02-01T12:59:30","slug":"246enlescolaconnuria","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/246enlescolaconnuria\/","title":{"rendered":"#246EnL\u2019EscolaConNuri\u00e1"},"content":{"rendered":"<p><iframe src=\"https:\/\/www.ivoox.com\/player_ej_167672207_6_1.html?c1=0ebeb7\" width=\"100%\" height=\"200\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\nEsta semana en L\u2019Escola con N\u00faria, hablamos de inmigraci\u00f3n y regularizaci\u00f3n con nuestro consultor pol\u00edtico e inmigrante m\u00e1s cercano Marco Gonz\u00e1lez. Seguimos con la amnist\u00eda en Venezuela, cientos de lideres pol\u00edticos la han recibido, pero eso si con limitaciones, veremos al final en que queda todo ello. Fracaso contra el buying, no ha sido como se esperaba los resultados del programa que se implanto en los colegios en Espa\u00f1a. Pullita musical y con sentido en la canci\u00f3n de Estrella Morente Vs Rosal\u00eda, el arte se merece un respeto en todos los sentidos. Cerramos con la #Opini\u00f3nDeMierda<\/p>","protected":false},"excerpt":{"rendered":"<p>Esta semana en L\u2019Escola con N\u00faria, hablamos de inmigraci\u00f3n y regularizaci\u00f3n con nuestro consultor pol\u00edtico e inmigrante m\u00e1s cercano Marco Gonz\u00e1lez. Seguimos con la amnist\u00eda en Venezuela, cientos de lideres pol\u00edticos la han recibido, pero eso si con limitaciones, veremos al final en que queda todo ello. Fracaso contra el buying, no ha sido como [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":77983,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2560],"tags":[2507,2643,2773],"class_list":["post-78603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-lescola-con-nuria","tag-internacional","tag-magazin","tag-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#246EnL\u2019EscolaConNuri\u00e1 - DLVRADIO<\/title>\n<meta name=\"description\" content=\"Esta semana en L\u2019Escola con N\u00faria, hablamos de inmigraci\u00f3n y regularizaci\u00f3n con nuestro consultor pol\u00edtico e inmigrante m\u00e1s cercano Marco Gonz\u00e1lez.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/246enlescolaconnuria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#246EnL\u2019EscolaConNuri\u00e1 - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"Esta semana en L\u2019Escola con N\u00faria, hablamos de inmigraci\u00f3n y regularizaci\u00f3n con nuestro consultor pol\u00edtico e inmigrante m\u00e1s cercano Marco Gonz\u00e1lez.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/246enlescolaconnuria\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-01T12:59:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"doominio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/246enlescolaconnuria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/246enlescolaconnuria\\\/\"},\"author\":{\"name\":\"doominio\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\"},\"headline\":\"#246EnL\u2019EscolaConNuri\u00e1\",\"datePublished\":\"2026-02-01T12:59:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/246enlescolaconnuria\\\/\"},\"wordCount\":111,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/246enlescolaconnuria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/En-LEscola-2025.png\",\"keywords\":[\"internacional\",\"magaz\u00edn\",\"pol\u00edtica\"],\"articleSection\":[\"En L'Escola con N\u00faria\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/246enlescolaconnuria\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/246enlescolaconnuria\\\/\",\"name\":\"#246EnL\u2019EscolaConNuri\u00e1 - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/246enlescolaconnuria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/246enlescolaconnuria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/En-LEscola-2025.png\",\"datePublished\":\"2026-02-01T12:59:30+00:00\",\"description\":\"Esta semana en L\u2019Escola con N\u00faria, hablamos de inmigraci\u00f3n y regularizaci\u00f3n con nuestro consultor pol\u00edtico e inmigrante m\u00e1s cercano Marco Gonz\u00e1lez.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/246enlescolaconnuria\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/246enlescolaconnuria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/246enlescolaconnuria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/En-LEscola-2025.png\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/En-LEscola-2025.png\",\"width\":1500,\"height\":1500,\"caption\":\"En L'Escola con N\u00faria #232\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/246enlescolaconnuria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#246EnL\u2019EscolaConNuri\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\",\"name\":\"doominio\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#246EnL\u2019EscolaConNuri\u00e1 - DLVRADIO","description":"Esta semana en L\u2019Escola con N\u00faria, hablamos de inmigraci\u00f3n y regularizaci\u00f3n con nuestro consultor pol\u00edtico e inmigrante m\u00e1s cercano Marco Gonz\u00e1lez.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/246enlescolaconnuria\/","og_locale":"en_US","og_type":"article","og_title":"#246EnL\u2019EscolaConNuri\u00e1 - DLVRADIO","og_description":"Esta semana en L\u2019Escola con N\u00faria, hablamos de inmigraci\u00f3n y regularizaci\u00f3n con nuestro consultor pol\u00edtico e inmigrante m\u00e1s cercano Marco Gonz\u00e1lez.","og_url":"https:\/\/dlvradio.es\/en\/246enlescolaconnuria\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2026-02-01T12:59:30+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png","type":"image\/png"}],"author":"doominio","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/246enlescolaconnuria\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/246enlescolaconnuria\/"},"author":{"name":"doominio","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa"},"headline":"#246EnL\u2019EscolaConNuri\u00e1","datePublished":"2026-02-01T12:59:30+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/246enlescolaconnuria\/"},"wordCount":111,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/246enlescolaconnuria\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png","keywords":["internacional","magaz\u00edn","pol\u00edtica"],"articleSection":["En L'Escola con N\u00faria"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/246enlescolaconnuria\/","url":"https:\/\/dlvradio.es\/246enlescolaconnuria\/","name":"#246EnL\u2019EscolaConNuri\u00e1 - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/246enlescolaconnuria\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/246enlescolaconnuria\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png","datePublished":"2026-02-01T12:59:30+00:00","description":"Esta semana en L\u2019Escola con N\u00faria, hablamos de inmigraci\u00f3n y regularizaci\u00f3n con nuestro consultor pol\u00edtico e inmigrante m\u00e1s cercano Marco Gonz\u00e1lez.","breadcrumb":{"@id":"https:\/\/dlvradio.es\/246enlescolaconnuria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/246enlescolaconnuria\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/246enlescolaconnuria\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png","width":1500,"height":1500,"caption":"En L'Escola con N\u00faria #232"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/246enlescolaconnuria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"#246EnL\u2019EscolaConNuri\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa","name":"doominio","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/78603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=78603"}],"version-history":[{"count":1,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/78603\/revisions"}],"predecessor-version":[{"id":78604,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/78603\/revisions\/78604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/77983"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=78603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=78603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=78603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}