{"id":78918,"date":"2026-03-30T10:00:03","date_gmt":"2026-03-30T08:00:03","guid":{"rendered":"https:\/\/dlvradio.es\/?p=78918"},"modified":"2026-03-29T21:38:26","modified_gmt":"2026-03-29T19:38:26","slug":"252enlescolaconnuria","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/252enlescolaconnuria\/","title":{"rendered":"#252EnL\u2019EscolaConN\u00faria"},"content":{"rendered":"<p><iframe src=\"https:\/\/www.ivoox.com\/player_ej_170961615_6_1.html?c1=0ebeb7\" width=\"100%\" height=\"200\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\nOs dejamos un nuevo programa de en L\u2019Escola con N\u00faria. Esta semana celebramos los 10 a\u00f1os musicales de <strong>DBALDOMEROS<\/strong>, para ello entrevistando a su guitarrista <strong>Pedro Velardo<\/strong>, con el hemos hablado de su trabajo en estos a\u00f1os y su futuro. Captan en Snapchat a un adolescente para atentar en Paris contra el Bankof America, un intento que fue una chapuza desde su inicio os lo contamos con todo detalle. El PSOE teme el sor pas\u00f3 de #OX en las pr\u00f3ximas elecciones en Andaluc\u00eda, seg\u00fan las encuestas, aunque en estas \u00faltimas lecciones auton\u00f3micas no han sido muy certeras la verdad. La nueva arzobispa. Cerramos con la #Opini\u00f3nDeMierda.<\/p>","protected":false},"excerpt":{"rendered":"<p>Os dejamos un nuevo programa de en L\u2019Escola con N\u00faria. Esta semana celebramos los 10 a\u00f1os musicales de DBALDOMEROS, para ello entrevistando a su guitarrista Pedro Velardo, con el hemos hablado de su trabajo en estos a\u00f1os y su futuro. Captan en Snapchat a un adolescente para atentar en Paris contra el Bankof America, un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":77983,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2560],"tags":[2530,2495,2643,2500],"class_list":["post-78918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-lescola-con-nuria","tag-actualidad","tag-entrevistas","tag-magazin","tag-musica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#252EnL\u2019EscolaConN\u00faria - DLVRADIO<\/title>\n<meta name=\"description\" content=\"Os dejamos un nuevo programa de en L\u2019Escola con N\u00faria. Esta semana celebramos los 10 a\u00f1os musicales de DBALDOMEROS, para ello entrevistando a su\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/252enlescolaconnuria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#252EnL\u2019EscolaConN\u00faria - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"Os dejamos un nuevo programa de en L\u2019Escola con N\u00faria. Esta semana celebramos los 10 a\u00f1os musicales de DBALDOMEROS, para ello entrevistando a su\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/252enlescolaconnuria\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-30T08:00:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"doominio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/252enlescolaconnuria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/252enlescolaconnuria\\\/\"},\"author\":{\"name\":\"doominio\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\"},\"headline\":\"#252EnL\u2019EscolaConN\u00faria\",\"datePublished\":\"2026-03-30T08:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/252enlescolaconnuria\\\/\"},\"wordCount\":117,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/252enlescolaconnuria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/En-LEscola-2025.png\",\"keywords\":[\"actualidad\",\"Entrevistas\",\"magaz\u00edn\",\"m\u00fasica\"],\"articleSection\":[\"En L'Escola con N\u00faria\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/252enlescolaconnuria\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/252enlescolaconnuria\\\/\",\"name\":\"#252EnL\u2019EscolaConN\u00faria - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/252enlescolaconnuria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/252enlescolaconnuria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/En-LEscola-2025.png\",\"datePublished\":\"2026-03-30T08:00:03+00:00\",\"description\":\"Os dejamos un nuevo programa de en L\u2019Escola con N\u00faria. Esta semana celebramos los 10 a\u00f1os musicales de DBALDOMEROS, para ello entrevistando a su\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/252enlescolaconnuria\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/252enlescolaconnuria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/252enlescolaconnuria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/En-LEscola-2025.png\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/En-LEscola-2025.png\",\"width\":1500,\"height\":1500,\"caption\":\"En L'Escola con N\u00faria #232\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/252enlescolaconnuria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#252EnL\u2019EscolaConN\u00faria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\",\"name\":\"doominio\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#252EnL\u2019EscolaConN\u00faria - DLVRADIO","description":"Os dejamos un nuevo programa de en L\u2019Escola con N\u00faria. Esta semana celebramos los 10 a\u00f1os musicales de DBALDOMEROS, para ello entrevistando a su","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/252enlescolaconnuria\/","og_locale":"en_US","og_type":"article","og_title":"#252EnL\u2019EscolaConN\u00faria - DLVRADIO","og_description":"Os dejamos un nuevo programa de en L\u2019Escola con N\u00faria. Esta semana celebramos los 10 a\u00f1os musicales de DBALDOMEROS, para ello entrevistando a su","og_url":"https:\/\/dlvradio.es\/en\/252enlescolaconnuria\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2026-03-30T08:00:03+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png","type":"image\/png"}],"author":"doominio","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/252enlescolaconnuria\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/252enlescolaconnuria\/"},"author":{"name":"doominio","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa"},"headline":"#252EnL\u2019EscolaConN\u00faria","datePublished":"2026-03-30T08:00:03+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/252enlescolaconnuria\/"},"wordCount":117,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/252enlescolaconnuria\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png","keywords":["actualidad","Entrevistas","magaz\u00edn","m\u00fasica"],"articleSection":["En L'Escola con N\u00faria"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/252enlescolaconnuria\/","url":"https:\/\/dlvradio.es\/252enlescolaconnuria\/","name":"#252EnL\u2019EscolaConN\u00faria - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/252enlescolaconnuria\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/252enlescolaconnuria\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png","datePublished":"2026-03-30T08:00:03+00:00","description":"Os dejamos un nuevo programa de en L\u2019Escola con N\u00faria. Esta semana celebramos los 10 a\u00f1os musicales de DBALDOMEROS, para ello entrevistando a su","breadcrumb":{"@id":"https:\/\/dlvradio.es\/252enlescolaconnuria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/252enlescolaconnuria\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/252enlescolaconnuria\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png","width":1500,"height":1500,"caption":"En L'Escola con N\u00faria #232"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/252enlescolaconnuria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"#252EnL\u2019EscolaConN\u00faria"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa","name":"doominio","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/78918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=78918"}],"version-history":[{"count":2,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/78918\/revisions"}],"predecessor-version":[{"id":78921,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/78918\/revisions\/78921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/77983"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=78918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=78918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=78918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}