{"id":78972,"date":"2026-04-19T13:03:47","date_gmt":"2026-04-19T11:03:47","guid":{"rendered":"https:\/\/dlvradio.es\/?p=78972"},"modified":"2026-04-19T13:03:47","modified_gmt":"2026-04-19T11:03:47","slug":"254enlescolaconnuria","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/254enlescolaconnuria\/","title":{"rendered":"#254EnL\u2019EscolaConN\u00faria"},"content":{"rendered":"<p><iframe src=\"https:\/\/www.ivoox.com\/player_ej_172158995_6_1.html?c1=0ebeb7\" width=\"100%\" height=\"200\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Como cada fin de semana volvemos con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria. Esta semana hablamos con la escritora Carmen Domingo de su nueva obra y de c\u00f3mo ser\u00e1 el d\u00eda del libro en Barcelona. Guerra en el L\u00edbano, uno de los muchos pa\u00edses que se ven afectados por los bombardeos de Israel y la complicidad de EE. UU. Acoso a Eduardo Mendoza por parte del nacionalismo catal\u00e1n. Se acaba el petrod\u00f3lar saud\u00ed para el deporte mundial, desde el futbol, pasando por el Golf y el tenis&#8230; Y como no cerramos con #LaOpini\u00f3nDeMierda.<\/p>","protected":false},"excerpt":{"rendered":"<p>Como cada fin de semana volvemos con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria. Esta semana hablamos con la escritora Carmen Domingo de su nueva obra y de c\u00f3mo ser\u00e1 el d\u00eda del libro en Barcelona. Guerra en el L\u00edbano, uno de los muchos pa\u00edses que se ven afectados por los bombardeos de Israel y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":77983,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2560],"tags":[2530,2495,2472,2643],"class_list":["post-78972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-lescola-con-nuria","tag-actualidad","tag-entrevistas","tag-informativos","tag-magazin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#254EnL\u2019EscolaConN\u00faria - DLVRADIO<\/title>\n<meta name=\"description\" content=\"Como cada fin de semana volvemos con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria. Esta semana hablamos con la escritora Carmen Domingo de su nueva obra y de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/254enlescolaconnuria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#254EnL\u2019EscolaConN\u00faria - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"Como cada fin de semana volvemos con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria. Esta semana hablamos con la escritora Carmen Domingo de su nueva obra y de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/254enlescolaconnuria\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-19T11:03:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"doominio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/254enlescolaconnuria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/254enlescolaconnuria\\\/\"},\"author\":{\"name\":\"doominio\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\"},\"headline\":\"#254EnL\u2019EscolaConN\u00faria\",\"datePublished\":\"2026-04-19T11:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/254enlescolaconnuria\\\/\"},\"wordCount\":107,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/254enlescolaconnuria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/En-LEscola-2025.png\",\"keywords\":[\"actualidad\",\"Entrevistas\",\"informativos\",\"magaz\u00edn\"],\"articleSection\":[\"En L'Escola con N\u00faria\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/254enlescolaconnuria\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/254enlescolaconnuria\\\/\",\"name\":\"#254EnL\u2019EscolaConN\u00faria - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/254enlescolaconnuria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/254enlescolaconnuria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/En-LEscola-2025.png\",\"datePublished\":\"2026-04-19T11:03:47+00:00\",\"description\":\"Como cada fin de semana volvemos con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria. Esta semana hablamos con la escritora Carmen Domingo de su nueva obra y de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/254enlescolaconnuria\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/254enlescolaconnuria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/254enlescolaconnuria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/En-LEscola-2025.png\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/En-LEscola-2025.png\",\"width\":1500,\"height\":1500,\"caption\":\"En L'Escola con N\u00faria #232\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/254enlescolaconnuria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#254EnL\u2019EscolaConN\u00faria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\",\"name\":\"doominio\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#254EnL\u2019EscolaConN\u00faria - DLVRADIO","description":"Como cada fin de semana volvemos con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria. Esta semana hablamos con la escritora Carmen Domingo de su nueva obra y de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/254enlescolaconnuria\/","og_locale":"en_US","og_type":"article","og_title":"#254EnL\u2019EscolaConN\u00faria - DLVRADIO","og_description":"Como cada fin de semana volvemos con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria. Esta semana hablamos con la escritora Carmen Domingo de su nueva obra y de","og_url":"https:\/\/dlvradio.es\/en\/254enlescolaconnuria\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2026-04-19T11:03:47+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png","type":"image\/png"}],"author":"doominio","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/254enlescolaconnuria\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/254enlescolaconnuria\/"},"author":{"name":"doominio","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa"},"headline":"#254EnL\u2019EscolaConN\u00faria","datePublished":"2026-04-19T11:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/254enlescolaconnuria\/"},"wordCount":107,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/254enlescolaconnuria\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png","keywords":["actualidad","Entrevistas","informativos","magaz\u00edn"],"articleSection":["En L'Escola con N\u00faria"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/254enlescolaconnuria\/","url":"https:\/\/dlvradio.es\/254enlescolaconnuria\/","name":"#254EnL\u2019EscolaConN\u00faria - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/254enlescolaconnuria\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/254enlescolaconnuria\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png","datePublished":"2026-04-19T11:03:47+00:00","description":"Como cada fin de semana volvemos con nuestro magaz\u00edn de en L\u2019Escola con N\u00faria. Esta semana hablamos con la escritora Carmen Domingo de su nueva obra y de","breadcrumb":{"@id":"https:\/\/dlvradio.es\/254enlescolaconnuria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/254enlescolaconnuria\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/254enlescolaconnuria\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2025\/10\/En-LEscola-2025.png","width":1500,"height":1500,"caption":"En L'Escola con N\u00faria #232"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/254enlescolaconnuria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"#254EnL\u2019EscolaConN\u00faria"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa","name":"doominio","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/78972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=78972"}],"version-history":[{"count":2,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/78972\/revisions"}],"predecessor-version":[{"id":78974,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/78972\/revisions\/78974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/77983"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=78972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=78972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=78972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}