{"id":79150,"date":"2026-05-28T21:42:05","date_gmt":"2026-05-28T19:42:05","guid":{"rendered":"https:\/\/dlvradio.es\/?p=79150"},"modified":"2026-05-28T21:42:05","modified_gmt":"2026-05-28T19:42:05","slug":"las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/","title":{"rendered":"Las formaciones pol\u00edticas de PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n"},"content":{"rendered":"<h3><strong>PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n bajo pretextos racistas y desprotegen a la infancia<\/strong><\/h3>\n<ul>\n<li><strong><em>Ecologistas en Acci\u00f3n exige mantener el programa escolar de consumo de frutas, hortalizas y leche, adaptando los pliegos para priorizar la producci\u00f3n local, de temporada y ecol\u00f3gica.<\/em><\/strong><\/li>\n<li><strong><em>La organizaci\u00f3n califica de \u00abesperpento racista\u00bb y \u00abprofunda ignorancia\u00bb las declaraciones de las derechas, que eliminan el programa usando la importaci\u00f3n extranjera como excusa, mientras alimentan con soja deforestada a millones de cerdos en Arag\u00f3n.<\/em><\/strong><\/li>\n<li><strong><em>El ecologismo social recuerda que el modelo que defienden PP y VOX expulsa a la agricultura familiar y se sostiene sobre la explotaci\u00f3n laboral de jornaleros y jornaleras migrantes.<\/em><\/strong><\/li>\n<\/ul>\n<p>Ante el anuncio de la nueva consejera de Agricultura, Ganader\u00eda y Alimentaci\u00f3n del Gobierno de Arag\u00f3n, Arancha Sim\u00f3n (VOX), de suspender de forma fulminante el programa escolar de consumo de frutas, hortalizas y leche, Ecologistas en Acci\u00f3n muestra su m\u00e1s absoluto rechazo y denuncia la preocupante hipocres\u00eda, incompetencia y demagogia racista que sostiene esta decisi\u00f3n del ejecutivo de coalici\u00f3n PP-VOX.<\/p>\n<p>Para la organizaci\u00f3n ecologista, suspender este programa con la excusa de evitar el consumo de peras de Sud\u00e1frica o naranjas de Egipto no es un acto de patriotismo agrario, sino la constataci\u00f3n de un fracaso de gesti\u00f3n absoluto: <em>\u201cEl Gobierno de Arag\u00f3n es el \u00fanico responsable de redactar los pliegos de condiciones de los concursos p\u00fablicos. Si en las escuelas aragonesas se ha repartido fruta importada, ha sido por la incapacidad de la Administraci\u00f3n para aprobar unos pliegos con criterios ambientales y de proximidad rigurosos, que favorezcan de forma legal y directa a la agricultura y ganader\u00eda de nuestros pueblos\u201d<\/em>.<\/p>\n<p><strong>Desmontando la hipocres\u00eda: soja transg\u00e9nica, deforestaci\u00f3n y el falso <em>\u00abpatriotismo de plato\u00bb<\/em><\/strong><\/p>\n<p>La demagogia del Ejecutivo auton\u00f3mico alcanz\u00f3 su punto m\u00e1s \u00e1lgido tras las pol\u00e9micas declaraciones del diputado de VOX, David Arranz, quien en las Cortes de Arag\u00f3n espet\u00f3 un expl\u00edcito \u00abme gustar\u00eda ver mucho cerdo en los comedores escolares\u00bb, en lo que Ecologistas en Acci\u00f3n califica como una deleznable muestra de racismo y provocaci\u00f3n xen\u00f3foba dirigida a la comunidad musulmana.<\/p>\n<p>M\u00e1s all\u00e1 del componente de odio, Ecologistas en Acci\u00f3n quiere desmontar t\u00e9cnicamente la monumental hipocres\u00eda econ\u00f3mica de PP y VOX: <em>\u201cDefender la eliminaci\u00f3n de la fruta importada mientras se exige el consumo masivo de porcino industrial denota una profunda ignorancia sobre c\u00f3mo funciona el modelo del agronegocio que ambos partidos defienden\u201d<\/em>.<\/p>\n<p>Adem\u00e1s, la ganader\u00eda industrial \u2014que representa casi la totalidad del porcino en Arag\u00f3n, donde se hacinan m\u00e1s de nueve millones de cerdos al a\u00f1o\u2014 depende de forma absoluta de la importaci\u00f3n masiva de piensos. Unos piensos elaborados con soja transg\u00e9nica importada de la otra punta del mundo, cultivada a costa de la deforestaci\u00f3n masiva de ecosistemas vitales como el Amazonas o el Cerrado en Brasil y Bolivia.<\/p>\n<p><strong>Ataque a la agricultura familiar y explotaci\u00f3n en el campo<\/strong><\/p>\n<p>Este ataque al programa escolar de consumo de frutas, hortalizas y leche no es un hecho aislado. Nada m\u00e1s llegar al Gobierno, PP y VOX modificaron de forma dr\u00e1stica la Ley de Agricultura Social y Familiar de Arag\u00f3n con el \u00fanico objetivo de desproteger a la peque\u00f1a producci\u00f3n local y abrir las puertas de par en par al acaparamiento de tierras por parte de grandes fondos de inversi\u00f3n especulativos y macroproyectos energ\u00e9ticos y agroindustriales.<\/p>\n<p>Para Ecologistas en Acci\u00f3n, resulta perverso que las derechas promuevan el odio a lo extranjero tambi\u00e9n en los comedores escolares, mientras sostienen un modelo agrario industrializado que se lucra y sobrevive gracias a la precarizaci\u00f3n extrema y la explotaci\u00f3n laboral de miles de personas migrantes en el campo.<\/p>\n<p><em>\u201cEl modelo de PP y VOX expulsa a las familias agricultoras aragonesas mientras condena a las personas temporeras extranjeras a la vulnerabilidad habitacional y a condiciones de trabajo indignas en las campa\u00f1as de recogida. La soberan\u00eda alimentaria no se consigue con discursos de exclusi\u00f3n, sino garantizando precios justos para los productores y plenos derechos laborales y sociales para los jornaleros que recogen nuestra comida\u201d<\/em>, a\u00f1aden.<\/p>\n<p><strong>Las soluciones existen: Compra p\u00fablica ecol\u00f3gica y comedores sostenibles<\/strong><\/p>\n<p>Frente al desmantelamiento de los servicios p\u00fablicos y la par\u00e1lisis institucional, Ecologistas en Acci\u00f3n, junto a la comunidad educativa, las AMPA y algunas organizaciones agrarias, recuerda que las soluciones reales est\u00e1n encima de la mesa y solo requieren voluntad pol\u00edtica:<\/p>\n<ol>\n<li><strong>Pliegos de condiciones con criterios de proximidad.<\/strong> Se exige a la Administraci\u00f3n p\u00fablica que utilice las herramientas legales existentes (como la Ley de Contratos del Sector P\u00fablico) para dise\u00f1ar concursos que primen los canales cortos de comercializaci\u00f3n, el residuo cero, la huella de carbono y los precios justos en origen. Adem\u00e1s de ayudar a la agricultura local, la compra de fruta y verdura de proximidad es m\u00e1s saludable ya que el porcentaje de alimentos contaminados por plaguicidas es la mitad en los alimentos locales que en los importados, seg\u00fan datos oficiales investigados por Ecologistas en Acci\u00f3n en su informe \u2018Directo a tus hormonas 2026\u2019.<\/li>\n<li><strong>Alimentaci\u00f3n sana y universal.<\/strong> El programa escolar de consumo de frutas, hortalizas y leche debe reactivarse de inmediato bajo criterios de producci\u00f3n fresca, de temporada y, de forma prioritaria, ecol\u00f3gica. Adem\u00e1s, este modelo debe extenderse de forma estructural al resto de la compra p\u00fablica: comedores escolares diarios, residencias de mayores y hospitales.<\/li>\n<\/ol>\n<p><strong>Nacho Escart\u00edn<\/strong>, portavoz de Ecologistas en Acci\u00f3n, ha declarado: <em>\u201cArag\u00f3n dispone de un sector frut\u00edcola de primer nivel en comarcas como Valdejal\u00f3n, el Bajo Cinca o la Comunidad de Calatayud, entre otras, que est\u00e1 perfectamente capacitado para abastecer a nuestras escuelas. Suspender el programa escolar de consumo de frutas, hortalizas y leche es una tremenda irresponsabilidad que paga la salud de la infancia aragonesa. Exigimos al Gobierno de Arag\u00f3n que rectifique, que cese su discurso de odio y exclusi\u00f3n, y que empiece a trabajar de una vez por el bien com\u00fan, la sostenibilidad y el futuro de nuestro territorio\u201d<\/em>.<\/p>","protected":false},"excerpt":{"rendered":"<p>PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n bajo pretextos racistas y desprotegen a la infancia Ecologistas en Acci\u00f3n exige mantener el programa escolar de consumo de frutas, hortalizas y leche, adaptando los pliegos para priorizar la producci\u00f3n local, de temporada y ecol\u00f3gica. La organizaci\u00f3n califica de \u00abesperpento racista\u00bb y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":79151,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2711,2465],"tags":[2528,2478,2466,2773],"class_list":["post-79150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emergencia-climatica","category-informativos","tag-activismo","tag-ecologia","tag-espana","tag-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las formaciones pol\u00edticas de PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n - DLVRADIO<\/title>\n<meta name=\"description\" content=\"PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n bajo pretextos racistas y desprotegen a la infancia Ecologistas en Acci\u00f3n exige\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las formaciones pol\u00edticas de PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n bajo pretextos racistas y desprotegen a la infancia Ecologistas en Acci\u00f3n exige\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-28T19:42:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2026\/05\/dlvradio-1500-x-1500-px-8-1024x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"doominio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\\\/\"},\"author\":{\"name\":\"doominio\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\"},\"headline\":\"Las formaciones pol\u00edticas de PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n\",\"datePublished\":\"2026-05-28T19:42:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\\\/\"},\"wordCount\":1077,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dlvradio-1500-x-1500-px-8.png\",\"keywords\":[\"activismo\",\"ecolog\u00eda\",\"Espa\u00f1a\",\"pol\u00edtica\"],\"articleSection\":[\"Emergencia clim\u00e1tica\",\"Informativos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\\\/\",\"name\":\"Las formaciones pol\u00edticas de PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dlvradio-1500-x-1500-px-8.png\",\"datePublished\":\"2026-05-28T19:42:05+00:00\",\"description\":\"PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n bajo pretextos racistas y desprotegen a la infancia Ecologistas en Acci\u00f3n exige\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dlvradio-1500-x-1500-px-8.png\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dlvradio-1500-x-1500-px-8.png\",\"width\":1500,\"height\":1500,\"caption\":\"Las formaciones pol\u00edticas de PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las formaciones pol\u00edticas de PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\",\"name\":\"doominio\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las formaciones pol\u00edticas de PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n - DLVRADIO","description":"PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n bajo pretextos racistas y desprotegen a la infancia Ecologistas en Acci\u00f3n exige","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/","og_locale":"en_US","og_type":"article","og_title":"Las formaciones pol\u00edticas de PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n - DLVRADIO","og_description":"PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n bajo pretextos racistas y desprotegen a la infancia Ecologistas en Acci\u00f3n exige","og_url":"https:\/\/dlvradio.es\/en\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2026-05-28T19:42:05+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2026\/05\/dlvradio-1500-x-1500-px-8-1024x1024.png","type":"image\/png"}],"author":"doominio","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/"},"author":{"name":"doominio","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa"},"headline":"Las formaciones pol\u00edticas de PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n","datePublished":"2026-05-28T19:42:05+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/"},"wordCount":1077,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2026\/05\/dlvradio-1500-x-1500-px-8.png","keywords":["activismo","ecolog\u00eda","Espa\u00f1a","pol\u00edtica"],"articleSection":["Emergencia clim\u00e1tica","Informativos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/","url":"https:\/\/dlvradio.es\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/","name":"Las formaciones pol\u00edticas de PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2026\/05\/dlvradio-1500-x-1500-px-8.png","datePublished":"2026-05-28T19:42:05+00:00","description":"PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n bajo pretextos racistas y desprotegen a la infancia Ecologistas en Acci\u00f3n exige","breadcrumb":{"@id":"https:\/\/dlvradio.es\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2026\/05\/dlvradio-1500-x-1500-px-8.png","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2026\/05\/dlvradio-1500-x-1500-px-8.png","width":1500,"height":1500,"caption":"Las formaciones pol\u00edticas de PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/las-formaciones-politicas-de-pp-y-vox-suspenden-el-programa-escolar-de-consumo-de-frutas-en-aragon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"Las formaciones pol\u00edticas de PP y VOX suspenden el programa escolar de consumo de frutas en Arag\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa","name":"doominio","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/79150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=79150"}],"version-history":[{"count":1,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/79150\/revisions"}],"predecessor-version":[{"id":79152,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/79150\/revisions\/79152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/79151"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=79150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=79150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=79150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}