{"id":79190,"date":"2026-06-05T12:48:54","date_gmt":"2026-06-05T10:48:54","guid":{"rendered":"https:\/\/dlvradio.es\/?p=79190"},"modified":"2026-06-05T12:48:54","modified_gmt":"2026-06-05T10:48:54","slug":"la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras","status":"publish","type":"post","link":"https:\/\/dlvradio.es\/en\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/","title":{"rendered":"La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a los vecinos de un barrio de Figueras"},"content":{"rendered":"<p><u>En la localidad de Figueras (Girona)<\/u><\/p>\n<p><strong>La Polic\u00eda Nacional <\/strong><strong>materializa la expulsi\u00f3n de un ciudadano extranjero \u201c<em>multirreincidente<\/em>\u201d que tenia atemorizados a los vecinos de un barrio de Figueras<\/strong><\/p>\n<ul>\n<li><em><strong>Fue fundamental la cooperaci\u00f3n y coordinaci\u00f3n con Mossos d\u00b4Esquadra para la localizaci\u00f3n de este individuo.<\/strong><\/em><\/li>\n<\/ul>\n<ul>\n<li><em><strong>El historial delictivo de este peligroso individuo inclu\u00eda numerosos antecedentes de extrema gravedad: robos con violencia e intimidaci\u00f3n, robos fuerza, hurtos, amenazas graves, incluso un homicidio en grado de tentativa entre otros.<\/strong><\/em><\/li>\n<\/ul>\n<ul>\n<li><em><strong>Se tuvo que dise\u00f1ar un despliegue de minuciosos dispositivos conjuntos de vigilancia entre Polic\u00eda Nacional y Mossos d\u00b4Escuadra para la localizaci\u00f3n de esta persona que resid\u00eda en un piso ocupado.<\/strong><\/em><\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong>Polic\u00eda Nacional ha logrado materializar la expulsi\u00f3n del territorio nacional en aplicaci\u00f3n de la Ley de Extranjer\u00eda de un var\u00f3n de nacionalidad senegalesa, que resid\u00eda de manera irregular en el municipio de Figueres, en la comarca del Alt Empord\u00e0 y que ten\u00eda atemorizados a los vecinos de un barrio de la localidad de Figueras (Girona).<\/p>\n<p>La medida se enmarca en la aplicaci\u00f3n de la legislaci\u00f3n vigente en materia de extranjer\u00eda y pone fin a un dilatado proceso administrativo iniciado hace m\u00e1s de dos a\u00f1os. La orden de expulsi\u00f3n fue dictada en marzo de 2024 por la Subdelegaci\u00f3n del Gobierno en Girona. Sin embargo, su ejecuci\u00f3n requiri\u00f3 de gestiones prolongadas tanto con las autoridades consulares del pa\u00eds de origen del deportado como con los organismos internos competentes, a fin de obtener la documentaci\u00f3n necesaria para hacer efectiva la repatriaci\u00f3n.<\/p>\n<p><strong><u>El delincuente generaba una honda alarma social entre los vecinos del barrio que hab\u00edan denunciado reiteradamente la conflictividad asociada a su presencia<\/u><\/strong><\/p>\n<p>El historial delictivo de este peligroso individuo inclu\u00eda numerosos antecedentes de extrema gravedad: robos con violencia e intimidaci\u00f3n, robos con fuerza en las cosas, hurtos, amenazas graves, atentado contra agentes de autoridad e incluso un homicidio en grado de tentativa. Sus continuas acciones delictivas hab\u00edan generado una honda alarma social y alteraban gravemente la convivencia pac\u00edfica en Figueres, especialmente en un barrio de la localidad, quienes hab\u00edan denunciado reiteradamente la conflictividad asociada a su presencia.<\/p>\n<p>Las investigaciones iniciales hab\u00edan sido trasladadas a la Polic\u00eda Nacional por entidades locales y por la propia polic\u00eda auton\u00f3mica. La localizaci\u00f3n del individuo presentaba una enorme dificultad t\u00e9cnica al carecer \u00e9ste de un domicilio fijo conocido. Ante este escenario, la Polic\u00eda Nacional estrech\u00f3 la colaboraci\u00f3n diaria con Mossos d\u2019Esquadra, dise\u00f1ando y desplegando minuciosos dispositivos conjuntos de vigilancia e inteligencia. Este esfuerzo coordinado dio sus frutos al lograr ubicar a este individuo en una casa okupada del\u00a0 barrio figuerense<\/p>\n<p>Verificada su localizaci\u00f3n y completados todos los tr\u00e1mites legales y de documentaci\u00f3n, el Grupo Operativo de Extranjer\u00eda de la Comisar\u00eda Local de Figueres (unidad altamente especializada en este tipo de procedimientos) procedi\u00f3 a su detenci\u00f3n y custodia. El expulsado fue trasladado hasta el aeropuerto de Madrid- Adolfo Su\u00e1rez, desde donde embarc\u00f3 en un vuelo con destino Senegal.<\/p>\n<p>Con esta exitosa operaci\u00f3n, la Polic\u00eda Nacional reafirma su compromiso en la lucha contra la <em>multirreincidencia<\/em> y la cooperaci\u00f3n diaria con otros cuerpos policiales.<\/p>","protected":false},"excerpt":{"rendered":"<p>En la localidad de Figueras (Girona) La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a los vecinos de un barrio de Figueras Fue fundamental la cooperaci\u00f3n y coordinaci\u00f3n con Mossos d\u00b4Esquadra para la localizaci\u00f3n de este individuo. El historial delictivo de este peligroso individuo inclu\u00eda numerosos antecedentes de extrema [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":79191,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2772],"tags":[2774,2613],"class_list":["post-79190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sucesos","tag-policia","tag-sucesos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a los vecinos de un barrio de Figueras - DLVRADIO<\/title>\n<meta name=\"description\" content=\"En la localidad de Figueras (Girona) La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dlvradio.es\/en\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a los vecinos de un barrio de Figueras - DLVRADIO\" \/>\n<meta property=\"og:description\" content=\"En la localidad de Figueras (Girona) La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dlvradio.es\/en\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/\" \/>\n<meta property=\"og:site_name\" content=\"DLVRADIO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RadioDLVradio\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-05T10:48:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dlvradio.es\/wp-content\/uploads\/2026\/06\/FOTO-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"doominio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RadioDlvradio\" \/>\n<meta name=\"twitter:site\" content=\"@RadioDlvradio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\\\/\"},\"author\":{\"name\":\"doominio\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\"},\"headline\":\"La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a los vecinos de un barrio de Figueras\",\"datePublished\":\"2026-06-05T10:48:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\\\/\"},\"wordCount\":579,\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/FOTO-1.jpg\",\"keywords\":[\"polic\u00eda\",\"sucesos\"],\"articleSection\":[\"Sucesos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\\\/\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\\\/\",\"name\":\"La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a los vecinos de un barrio de Figueras - DLVRADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/FOTO-1.jpg\",\"datePublished\":\"2026-06-05T10:48:54+00:00\",\"description\":\"En la localidad de Figueras (Girona) La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dlvradio.es\\\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/FOTO-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dlvradio.es\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/FOTO-1.jpg\",\"width\":1600,\"height\":1200,\"caption\":\"La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a los vecinos de un barrio de Figueras\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dlvradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a los vecinos de un barrio de Figueras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#website\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"name\":\"DLVRADIO\",\"description\":\"Somos un medio de comunicaci\u00f3n alternativo a los medios tradicionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dlvradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#organization\",\"name\":\"DLVRADIO\",\"url\":\"https:\\\/\\\/dlvradio.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"DLVRADIO\"},\"image\":{\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RadioDLVradio\\\/\",\"https:\\\/\\\/x.com\\\/RadioDlvradio\",\"https:\\\/\\\/www.instagram.com\\\/radiodlvradio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dlvradio.es\\\/#\\\/schema\\\/person\\\/6ee60897fbb7fb4ad6634c73f4be87fa\",\"name\":\"doominio\",\"sameAs\":[\"https:\\\/\\\/dlvradio.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a los vecinos de un barrio de Figueras - DLVRADIO","description":"En la localidad de Figueras (Girona) La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dlvradio.es\/en\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/","og_locale":"en_US","og_type":"article","og_title":"La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a los vecinos de un barrio de Figueras - DLVRADIO","og_description":"En la localidad de Figueras (Girona) La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a","og_url":"https:\/\/dlvradio.es\/en\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/","og_site_name":"DLVRADIO","article_publisher":"https:\/\/www.facebook.com\/RadioDLVradio\/","article_published_time":"2026-06-05T10:48:54+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2026\/06\/FOTO-1.jpg","type":"image\/jpeg"}],"author":"doominio","twitter_card":"summary_large_image","twitter_creator":"@RadioDlvradio","twitter_site":"@RadioDlvradio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dlvradio.es\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/#article","isPartOf":{"@id":"https:\/\/dlvradio.es\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/"},"author":{"name":"doominio","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa"},"headline":"La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a los vecinos de un barrio de Figueras","datePublished":"2026-06-05T10:48:54+00:00","mainEntityOfPage":{"@id":"https:\/\/dlvradio.es\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/"},"wordCount":579,"publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"image":{"@id":"https:\/\/dlvradio.es\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2026\/06\/FOTO-1.jpg","keywords":["polic\u00eda","sucesos"],"articleSection":["Sucesos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dlvradio.es\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/","url":"https:\/\/dlvradio.es\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/","name":"La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a los vecinos de un barrio de Figueras - DLVRADIO","isPartOf":{"@id":"https:\/\/dlvradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dlvradio.es\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/#primaryimage"},"image":{"@id":"https:\/\/dlvradio.es\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/#primaryimage"},"thumbnailUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2026\/06\/FOTO-1.jpg","datePublished":"2026-06-05T10:48:54+00:00","description":"En la localidad de Figueras (Girona) La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a","breadcrumb":{"@id":"https:\/\/dlvradio.es\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dlvradio.es\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/#primaryimage","url":"https:\/\/dlvradio.es\/wp-content\/uploads\/2026\/06\/FOTO-1.jpg","contentUrl":"https:\/\/dlvradio.es\/wp-content\/uploads\/2026\/06\/FOTO-1.jpg","width":1600,"height":1200,"caption":"La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a los vecinos de un barrio de Figueras"},{"@type":"BreadcrumbList","@id":"https:\/\/dlvradio.es\/la-policia-nacional-materializa-la-expulsion-de-un-ciudadano-extranjero-multirreincidente-que-tenia-atemorizados-a-los-vecinos-de-un-barrio-de-figueras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dlvradio.es\/"},{"@type":"ListItem","position":2,"name":"La Polic\u00eda Nacional materializa la expulsi\u00f3n de un ciudadano extranjero \u201cmultirreincidente\u201d que tenia atemorizados a los vecinos de un barrio de Figueras"}]},{"@type":"WebSite","@id":"https:\/\/dlvradio.es\/#website","url":"https:\/\/dlvradio.es\/","name":"DLVRADIO","description":"We are an alternative media to traditional media","publisher":{"@id":"https:\/\/dlvradio.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dlvradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dlvradio.es\/#organization","name":"DLVRADIO","url":"https:\/\/dlvradio.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"DLVRADIO"},"image":{"@id":"https:\/\/dlvradio.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RadioDLVradio\/","https:\/\/x.com\/RadioDlvradio","https:\/\/www.instagram.com\/radiodlvradio\/"]},{"@type":"Person","@id":"https:\/\/dlvradio.es\/#\/schema\/person\/6ee60897fbb7fb4ad6634c73f4be87fa","name":"doominio","sameAs":["https:\/\/dlvradio.es"]}]}},"_links":{"self":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/79190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/comments?post=79190"}],"version-history":[{"count":1,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/79190\/revisions"}],"predecessor-version":[{"id":79192,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/posts\/79190\/revisions\/79192"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media\/79191"}],"wp:attachment":[{"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/media?parent=79190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/categories?post=79190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dlvradio.es\/en\/wp-json\/wp\/v2\/tags?post=79190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}